{"id":23,"date":"2025-09-03T08:27:34","date_gmt":"2025-09-03T08:27:34","guid":{"rendered":"https:\/\/flexora.vamtam.com\/?page_id=23"},"modified":"2026-07-08T16:09:26","modified_gmt":"2026-07-08T16:09:26","slug":"behandelingen","status":"publish","type":"page","link":"https:\/\/asianmassage.be\/fr\/behandelingen\/","title":{"rendered":"Behandelingen"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"23\" class=\"elementor elementor-23\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bb2d48 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"0bb2d48\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c92d56 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8c92d56\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:50}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos traitements<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed56591 elementor-widget elementor-widget-text-editor\" data-id=\"ed56591\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Les massages \u00e9rotiques ou sensuels ne font pas partie de notre offre.<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-108717e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"108717e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f7b4c90 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"f7b4c90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-195295f elementor-widget elementor-widget-image\" data-id=\"195295f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Aromatherapy-200x200-1.png\" class=\"attachment-full size-full wp-image-987810\" alt=\"\" srcset=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Aromatherapy-200x200-1.png 200w, https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Aromatherapy-200x200-1-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d78698 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2d78698\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 512 512\"><path d=\"M0 0 C5.28 0 10.56 0 16 0 C16 8.25 16 16.5 16 25 C17.65 25.66 19.3 26.32 21 27 C22.87890625 28.2265625 22.87890625 28.2265625 24.5625 29.625 C25.12066406 30.07101563 25.67882812 30.51703125 26.25390625 30.9765625 C33.11068752 38.9224522 32.48746287 47.12736902 32.25 57 C32.22990336 58.45700669 32.21165818 59.91404015 32.1953125 61.37109375 C32.15499191 64.91527334 32.07667994 68.4556828 32 72 C37.28 72 42.56 72 48 72 C47.95359375 69.855 47.9071875 67.71 47.859375 65.5 C47.82808648 63.39829875 47.80385208 61.29662448 47.78027344 59.19482422 C47.76028705 57.74581083 47.73308803 56.29687675 47.69824219 54.84814453 C47.47713952 45.41226287 47.42945608 38.20434981 54 30.72265625 C54.66 30.17480469 55.32 29.62695312 56 29.0625 C56.66 28.49660156 57.32 27.93070313 58 27.34765625 C60 26 60 26 64 25 C64 16.75 64 8.5 64 0 C69.28 0 74.56 0 80 0 C80 8.25 80 16.5 80 25 C81.65 25.66 83.3 26.32 85 27 C86.87890625 28.2265625 86.87890625 28.2265625 88.5625 29.625 C89.12066406 30.07101563 89.67882812 30.51703125 90.25390625 30.9765625 C97.11068752 38.9224522 96.48746287 47.12736902 96.25 57 C96.22990336 58.45700669 96.21165818 59.91404015 96.1953125 61.37109375 C96.15499191 64.91527334 96.07667994 68.4556828 96 72 C101.28 72 106.56 72 112 72 C111.95359375 69.855 111.9071875 67.71 111.859375 65.5 C111.82808648 63.39829875 111.80385208 61.29662448 111.78027344 59.19482422 C111.76028705 57.74581083 111.73308803 56.29687675 111.69824219 54.84814453 C111.47713952 45.41226287 111.42945608 38.20434981 118 30.72265625 C118.66 30.17480469 119.32 29.62695312 120 29.0625 C120.66 28.49660156 121.32 27.93070313 122 27.34765625 C124 26 124 26 128 25 C128 16.75 128 8.5 128 0 C133.28 0 138.56 0 144 0 C144 8.25 144 16.5 144 25 C145.65 25.66 147.3 26.32 149 27 C150.87890625 28.2265625 150.87890625 28.2265625 152.5625 29.625 C153.12066406 30.07101563 153.67882812 30.51703125 154.25390625 30.9765625 C161.11068752 38.9224522 160.48746287 47.12736902 160.25 57 C160.22990336 58.45700669 160.21165818 59.91404015 160.1953125 61.37109375 C160.15156901 64.9146255 160.08271767 68.45713877 160 72 C160.59975647 71.99111755 161.19951294 71.98223511 161.81744385 71.9730835 C168.11257302 71.88394603 174.40752022 71.82399292 180.703125 71.78027344 C183.04629815 71.76027389 185.38942214 71.73306523 187.73242188 71.69824219 C191.11861371 71.64920875 194.50414041 71.62691379 197.890625 71.609375 C198.92237854 71.58872986 199.95413208 71.56808472 201.01715088 71.54681396 C214.94795238 71.54260569 225.67236582 76.96257244 235.75 86.3125 C245.49771135 96.61196859 248.46157532 108.27806578 248.40405273 122.11572266 C248.41434761 123.8689106 248.41434761 123.8689106 248.42485046 125.65751648 C248.44304475 129.49315788 248.43929239 133.32838752 248.43359375 137.1640625 C248.43700319 139.16554562 248.44042141 141.16702893 248.44494683 143.16850984 C248.45894168 149.44962439 248.45747121 155.73060275 248.44604492 162.01171875 C248.43455045 168.47278004 248.44867276 174.93342687 248.4754414 181.39443362 C248.49764244 186.96332123 248.50422645 192.53207913 248.49836498 198.10100782 C248.49500684 201.41782362 248.49906119 204.7343159 248.51461601 208.0511055 C248.52951934 211.74873872 248.51885334 215.44546138 248.50170898 219.14306641 C248.51137695 220.23003311 248.52104492 221.31699982 248.53100586 222.43690491 C248.45727211 230.04454389 247.18521817 235.36517847 242.03515625 241.2421875 C241.38417969 241.78101563 240.73320312 242.31984375 240.0625 242.875 C239.41410156 243.42929687 238.76570313 243.98359375 238.09765625 244.5546875 C233.37452097 247.80898927 229.06066193 248.29025952 223.44176006 248.25726891 C222.68537295 248.26077498 221.92898584 248.26428105 221.1496779 248.26789337 C218.60660427 248.27722214 216.06375891 248.27228027 213.52067566 248.26742554 C211.68239906 248.27116105 209.84412405 248.27576218 208.00585157 248.28115618 C202.94747315 248.29341378 197.88916074 248.29312247 192.83077085 248.29076743 C187.37801996 248.29035996 181.92529043 248.30139171 176.47254944 248.31088257 C165.78703547 248.3275086 155.10154356 248.33299284 144.41601773 248.33410732 C135.73199093 248.33505703 127.04797141 248.33916342 118.36394691 248.34550858 C93.75347189 248.36312525 69.14301331 248.3723589 44.53253206 248.37084763 C43.86914225 248.37080774 43.20575243 248.37076785 42.5222599 248.37072675 C41.18072379 248.37064587 39.83918768 248.37056228 38.49765157 248.37047596 C17.62527827 248.36925044 -3.24703006 248.38426349 -24.11938477 248.41162109 C-47.56690953 248.4423413 -71.01439866 248.45952829 -94.46194571 248.45769465 C-106.87786191 248.45703012 -119.29370483 248.46255006 -131.70960426 248.48405075 C-142.28019601 248.50223831 -152.85068126 248.50662982 -163.42128185 248.4930319 C-168.81566706 248.48649007 -174.20984781 248.48642898 -179.60421371 248.5037384 C-184.54210349 248.51942029 -189.47962587 248.51665547 -194.41750642 248.49917014 C-196.20416474 248.49608947 -197.99085014 248.49977263 -199.77747653 248.51089029 C-217.73331939 248.61522708 -217.73331939 248.61522708 -225.2421875 242.03515625 C-226.05042969 241.05869141 -226.05042969 241.05869141 -226.875 240.0625 C-227.42929688 239.41410156 -227.98359375 238.76570312 -228.5546875 238.09765625 C-231.55275116 233.7464125 -232.25398943 229.96882562 -232.29052734 224.73193359 C-232.30328705 223.48648773 -232.31604675 222.24104187 -232.32919312 220.95785522 C-232.33225233 219.60471757 -232.33447925 218.25157782 -232.3359375 216.8984375 C-232.34237317 215.49703844 -232.3491021 214.0956407 -232.35610962 212.69424438 C-232.368069 209.75723157 -232.37179217 206.82033621 -232.37060547 203.88330078 C-232.37040312 200.14790937 -232.39762286 196.41328597 -232.43214989 192.67807579 C-232.45456756 189.78155166 -232.4584384 186.88520744 -232.45738602 183.9886055 C-232.45972286 182.61329139 -232.46843643 181.23797083 -232.48405075 179.86274338 C-232.61846895 166.79331526 -230.18214942 156.6185288 -221 147 C-208.92861067 135.47627295 -195.95386357 135.41855853 -180.1875 135.4609375 C-178.16690006 135.45101373 -176.14630916 135.43906615 -174.12573242 135.42520142 C-168.82983527 135.39297903 -163.53414469 135.38246049 -158.23815918 135.37835693 C-149.76402714 135.36957197 -141.29006365 135.33382224 -132.81607056 135.2861824 C-129.87430338 135.27369975 -126.9327548 135.27434622 -123.9909668 135.27645874 C-107.23054736 135.38378648 -107.23054736 135.38378648 -91.5625 130 C-90.11037109 129.2265625 -90.11037109 129.2265625 -88.62890625 128.4375 C-87.76136719 127.963125 -86.89382812 127.48875 -86 127 C-85.26652344 126.690625 -84.53304687 126.38125 -83.77734375 126.0625 C-81.50015451 124.70119127 -81.0408281 123.40775255 -80 121 C-79.16148767 119.76010143 -78.30563259 118.53184293 -77.4375 117.3125 C-74.90875962 113.60531751 -72.83666838 109.79834333 -70.82080078 105.80102539 C-62.55429338 89.47280343 -51.53349757 79.00156494 -34 73 C-30.00989572 72.01407181 -26.29095275 71.89605098 -22.1875 71.9375 C-21.02605469 71.94652344 -19.86460937 71.95554687 -18.66796875 71.96484375 C-17.78753906 71.97644531 -16.90710938 71.98804688 -16 72 C-16.02094727 71.1028125 -16.04189453 70.205625 -16.06347656 69.28125 C-16.13207616 65.91900141 -16.18200294 62.55750765 -16.21972656 59.19482422 C-16.23971295 57.74581083 -16.26691197 56.29687675 -16.30175781 54.84814453 C-16.52286048 45.41226287 -16.57054392 38.20434981 -10 30.72265625 C-9.34 30.17480469 -8.68 29.62695312 -8 29.0625 C-7.34 28.49660156 -6.68 27.93070313 -6 27.34765625 C-4 26 -4 26 0 25 C0 16.75 0 8.5 0 0 Z M2.6875 42.8125 C-0.04539483 46.35514144 -0.12057706 49.21093601 -0.09765625 53.54296875 C-0.09443359 54.61611328 -0.09121094 55.68925781 -0.08789062 56.79492188 C-0.07951172 57.91447266 -0.07113281 59.03402344 -0.0625 60.1875 C-0.05798828 61.31865234 -0.05347656 62.44980469 -0.04882812 63.61523438 C-0.03703511 66.41017876 -0.01909957 69.20509599 0 72 C5.28 72 10.56 72 16 72 C16.0811135 68.12457723 16.1405605 64.25086118 16.1875 60.375 C16.21263672 59.28058594 16.23777344 58.18617188 16.26367188 57.05859375 C16.36948569 49.09976243 16.36948569 49.09976243 13 42 C9.20468521 40.10234261 6.02678035 40.19522621 2.6875 42.8125 Z M66.6875 42.8125 C63.95460517 46.35514144 63.87942294 49.21093601 63.90234375 53.54296875 C63.90556641 54.61611328 63.90878906 55.68925781 63.91210938 56.79492188 C63.92048828 57.91447266 63.92886719 59.03402344 63.9375 60.1875 C63.94201172 61.31865234 63.94652344 62.44980469 63.95117188 63.61523438 C63.96296489 66.41017876 63.98090043 69.20509599 64 72 C69.28 72 74.56 72 80 72 C80.0811135 68.12457723 80.1405605 64.25086118 80.1875 60.375 C80.21263672 59.28058594 80.23777344 58.18617188 80.26367188 57.05859375 C80.36948569 49.09976243 80.36948569 49.09976243 77 42 C73.20468521 40.10234261 70.02678035 40.19522621 66.6875 42.8125 Z M130.6875 42.8125 C127.95460517 46.35514144 127.87942294 49.21093601 127.90234375 53.54296875 C127.90556641 54.61611328 127.90878906 55.68925781 127.91210938 56.79492188 C127.92048828 57.91447266 127.92886719 59.03402344 127.9375 60.1875 C127.94201172 61.31865234 127.94652344 62.44980469 127.95117188 63.61523438 C127.96296489 66.41017876 127.98090043 69.20509599 128 72 C133.28 72 138.56 72 144 72 C144.0811135 68.12457723 144.1405605 64.25086118 144.1875 60.375 C144.21263672 59.28058594 144.23777344 58.18617188 144.26367188 57.05859375 C144.36948569 49.09976243 144.36948569 49.09976243 141 42 C137.20468521 40.10234261 134.02678035 40.19522621 130.6875 42.8125 Z M-42 96 C-42.9075 96.5775 -43.815 97.155 -44.75 97.75 C-50.34667428 103.34667428 -54.05051752 109.97755081 -57.60058594 116.98510742 C-65.59068282 132.75253807 -74.90133116 142.80820429 -91.7109375 149.2734375 C-97.16374468 151.004192 -102.29078751 151.15588761 -107.96191406 151.17358398 C-108.85526962 151.180271 -109.74862518 151.18695801 -110.66905212 151.19384766 C-112.60494896 151.20787055 -114.54086207 151.21977333 -116.47678375 151.22979546 C-119.54616693 151.24625756 -122.61543023 151.26949875 -125.68475342 151.29469299 C-134.41037987 151.3653166 -143.13605549 151.42547958 -151.86181641 151.47680664 C-157.20391811 151.50870531 -162.54588159 151.55000873 -167.88787079 151.59700203 C-169.91790009 151.61295728 -171.94796119 151.62530852 -173.97803497 151.63390923 C-176.82566763 151.64614603 -179.67297896 151.67033093 -182.52050781 151.69702148 C-183.76461678 151.6979052 -183.76461678 151.6979052 -185.03385925 151.69880676 C-194.0765086 151.81037661 -202.00878065 152.9728726 -208.62890625 159.640625 C-214.27645944 165.90056347 -215.60123821 171.21557916 -215.4296875 179.640625 C-214.5932103 186.18035583 -211.73368019 190.8004872 -206.62109375 194.9140625 C-199.84330929 199.28081829 -193.63273108 200.09406741 -185.63136292 200.1942749 C-184.3964209 200.21154633 -183.16147888 200.22881775 -181.88911438 200.24661255 C-180.53878966 200.26061314 -179.18846303 200.27443155 -177.83813477 200.28808594 C-176.40182185 200.30583163 -174.96551208 200.32383366 -173.52920532 200.34207153 C-160.46682791 200.5004864 -147.40345022 200.58532146 -134.34031773 200.65206528 C-124.69397509 200.70236107 -115.04932529 200.78846438 -105.40375096 200.92068648 C-98.60782219 201.0106981 -91.81235842 201.05851228 -85.01586002 201.07564378 C-80.96152359 201.08709516 -76.90936238 201.11730129 -72.85568428 201.19359589 C-69.04217111 201.26461353 -65.2319035 201.28323467 -61.41781998 201.26247787 C-60.02293361 201.26390162 -58.62791466 201.28401392 -57.2336216 201.32471848 C-49.1424664 201.59405252 -49.1424664 201.59405252 -42.4466362 197.62249184 C-40.39095087 194.83110402 -38.67048952 192.03414195 -37 189 C-36.01699787 187.50945899 -35.02366379 186.02557984 -34.01220703 184.55419922 C-33.09141678 183.13942217 -32.17330964 181.72289545 -31.2578125 180.3046875 C-30.24488244 178.74994085 -29.23185912 177.19525497 -28.21875 175.640625 C-26.65689779 173.23640325 -25.09661888 170.83117955 -23.53808594 168.42480469 C-22.01115352 166.06964144 -20.47858109 163.71822882 -18.9453125 161.3671875 C-18.24379562 160.27831741 -18.24379562 160.27831741 -17.52810669 159.16744995 C-14.22644964 154.11322482 -14.22644964 154.11322482 -12 153 C-10.09091814 152.8800592 -8.17777752 152.82268712 -6.26513672 152.79467773 C-5.06404266 152.77473251 -3.86294861 152.75478729 -2.62545776 152.73423767 C-1.32335358 152.71752518 -0.02124939 152.70081268 1.3203125 152.68359375 C2.66267538 152.66302375 4.00503179 152.64202727 5.34738159 152.62062073 C8.88188438 152.56540469 12.41644557 152.51599342 15.9510498 152.46777344 C19.55726322 152.41755496 23.16339172 152.36187071 26.76953125 152.30664062 C33.84628198 152.19906481 40.92311098 152.09812361 48 152 C48 157.28 48 162.56 48 168 C45.74542969 167.91359253 45.74542969 167.91359253 43.4453125 167.82543945 C37.84758071 167.62574299 32.25016032 167.499853 26.64990234 167.39575195 C24.23041786 167.34056505 21.81129811 167.26559238 19.39306641 167.17016602 C6.21033411 166.11400563 6.21033411 166.11400563 -5.99267578 169.86035156 C-8.15428809 172.7763783 -9.50307393 175.69221046 -11 179 C-12.82671366 181.95715652 -14.79432145 184.81700318 -16.7421875 187.6953125 C-17.75880677 189.24764935 -18.77179756 190.80236819 -19.78125 192.359375 C-20.28914062 193.14119141 -20.79703125 193.92300781 -21.3203125 194.72851562 C-22.36812721 196.34367724 -23.4153147 197.9592459 -24.46191406 199.57519531 C-25.98884648 201.93035856 -27.52141891 204.28177118 -29.0546875 206.6328125 C-29.75620438 207.72168259 -29.75620438 207.72168259 -30.47189331 208.83255005 C-33.77355036 213.88677518 -33.77355036 213.88677518 -36 215 C-38.13930114 215.10508017 -40.28194043 215.14394876 -42.42379761 215.15390015 C-43.09082581 215.1582824 -43.75785401 215.16266465 -44.44509518 215.1671797 C-46.69110141 215.18058558 -48.93706839 215.18675074 -51.18310547 215.19287109 C-52.78952716 215.20077114 -54.39594708 215.20904003 -56.00236511 215.21765137 C-61.29062194 215.24389956 -66.57888676 215.25918941 -71.8671875 215.2734375 C-73.68896617 215.27879748 -75.51074478 215.28417499 -77.33252335 215.28956985 C-84.91584271 215.31120949 -92.49915992 215.32994239 -100.08250237 215.34119225 C-110.93824834 215.35740306 -121.79363472 215.39049843 -132.64924514 215.44759309 C-140.28677709 215.48638554 -147.92421329 215.50583637 -155.56184113 215.51111281 C-160.11973839 215.51475574 -164.67725237 215.52666239 -169.23504257 215.55921555 C-173.53122315 215.5894575 -177.82679188 215.59555112 -182.12305641 215.58383179 C-183.69189684 215.58361234 -185.26076696 215.59180958 -186.82950783 215.60948563 C-196.6002751 215.71349837 -204.19005213 214.41079023 -213 210 C-213.99 209.67 -214.98 209.34 -216 209 C-216.0816082 211.37570543 -216.14077222 213.74855841 -216.1875 216.125 C-216.22520508 217.12273437 -216.22520508 217.12273437 -216.26367188 218.140625 C-216.33309743 222.8615625 -215.67504844 226.08897473 -213 230 C-208.89006023 232.19220859 -205.26011105 232.25142183 -200.65481663 232.25447559 C-199.55479302 232.25928531 -199.55479302 232.25928531 -198.43254671 232.26419219 C-195.9678558 232.27251327 -193.50340656 232.26656058 -191.03871155 232.26069641 C-189.25675704 232.26371613 -187.47480383 232.26760471 -185.69285291 232.27228898 C-180.79023121 232.2826008 -175.88768238 232.28037907 -170.98505461 232.27610838 C-165.70003503 232.27364694 -160.41503325 232.28264805 -155.13002014 232.29014587 C-144.77404166 232.30291093 -134.41808908 232.30468433 -124.06210405 232.30234561 C-115.64693908 232.30056438 -107.23178199 232.3023079 -98.81661797 232.30657005 C-97.6200717 232.30716524 -96.42352543 232.30776043 -95.19072018 232.30837366 C-92.76013824 232.30958537 -90.32955629 232.31079951 -87.89897435 232.31201603 C-65.09278857 232.32289844 -42.28661757 232.32072571 -19.48043095 232.31463119 C1.39563033 232.30946088 22.27164497 232.32071925 43.14769702 232.33972941 C64.5706638 232.35908843 85.99360849 232.36736724 107.41658407 232.36360615 C119.44900743 232.36169123 131.48139106 232.36420997 143.5138073 232.37832069 C153.75652848 232.39021078 163.9991855 232.39166606 174.24190753 232.37953053 C179.46994023 232.37362527 184.69785543 232.37258778 189.92588043 232.38453293 C194.70941367 232.39533569 199.49273053 232.39235556 204.27625341 232.37827124 C206.00903896 232.3756088 207.74184117 232.37803904 209.47461044 232.38600711 C211.82632839 232.39607287 214.17728829 232.3877262 216.52897549 232.37473011 C217.83630026 232.37478513 219.14362504 232.37484014 220.49056572 232.37489682 C224.31843561 231.96598298 226.73894756 231.01572018 230 229 C232.28018459 225.20034858 232.24347986 221.64390244 232.22705078 217.28198242 C232.22748886 216.30065338 232.22748886 216.30065338 232.22793579 215.29949951 C232.22654982 213.15135121 232.21102371 211.00355596 232.1953125 208.85546875 C232.19157975 207.3604603 232.18873402 205.8654494 232.18673706 204.37043762 C232.17912118 200.44622986 232.15949041 196.52217145 232.1373291 192.59802246 C232.11682649 188.5894574 232.10772592 184.58086807 232.09765625 180.57226562 C232.07624245 172.71477541 232.04213138 164.85740631 232 157 C231.12601562 157.58007812 231.12601562 157.58007812 230.234375 158.171875 C229.41453125 158.69265625 228.5946875 159.2134375 227.75 159.75 C226.96109375 160.26046875 226.1721875 160.7709375 225.359375 161.296875 C216.44098875 165.81828942 208.11375034 167.5947881 198.17285156 167.54589844 C197.0591922 167.55623611 195.94553284 167.56657379 194.79812622 167.57722473 C191.16214102 167.60643264 187.5267178 167.60814728 183.890625 167.609375 C181.35185702 167.62437145 178.81309874 167.64110165 176.27435303 167.65948486 C170.30361996 167.6985711 164.33298734 167.72033319 158.36215568 167.73345876 C151.55658985 167.74940424 144.75120687 167.78785091 137.94574785 167.82805204 C123.963889 167.91014847 109.98204592 167.96363081 96 168 C96 162.72 96 157.44 96 152 C97.27849319 152.00444122 98.55698639 152.00888245 99.8742218 152.01345825 C111.95273975 152.05409115 124.03124373 152.08402602 136.10981464 152.10362434 C142.31876295 152.11403889 148.52765584 152.12815549 154.73657227 152.15087891 C160.73419422 152.17269039 166.73176304 152.18458613 172.72942162 152.18975449 C175.01182071 152.19343536 177.29421706 152.20062302 179.5765934 152.21146011 C182.78590693 152.22608541 185.99500394 152.22797334 189.2043457 152.22705078 C190.13727448 152.23424133 191.07020325 152.24143188 192.03140259 152.24884033 C203.84083525 152.21236734 213.75507404 150.37241875 222.81640625 142.40234375 C228.84876036 136.00714128 231.21698346 128.68860785 231.5 120 C231.18508124 110.63370648 228.45467121 103.56621497 221.97265625 96.75390625 C209.95147447 86.06576641 193.87753116 87.709148 178.83813477 87.74121094 C176.69837322 87.73849758 174.55861261 87.73493472 172.41885376 87.73059082 C166.63167043 87.72150503 160.84455875 87.72499549 155.05737424 87.73134899 C148.9864847 87.73642939 142.9156011 87.73171182 136.8447113 87.72857666 C126.65061345 87.72494268 116.45654462 87.72972092 106.26245117 87.73925781 C94.49668156 87.75013833 82.73098129 87.74661739 70.96521336 87.735605 C60.84343804 87.72651246 50.72168352 87.72525656 40.59990543 87.73048234 C34.5634087 87.7335916 28.52694451 87.73404021 22.49044991 87.72740936 C16.81292749 87.721608 11.13549398 87.72568371 5.45798111 87.73719788 C3.38120229 87.7398297 1.30441591 87.73910481 -0.77235985 87.73467255 C-22.38648187 87.6651168 -22.38648187 87.6651168 -42 96 Z \" fill=\"#FFFFFF\" transform=\"translate(248,184)\"><\/path><path d=\"M0 0 C2.44225447 1.66159248 4.74768159 3.38773224 7.0390625 5.25 C7.87179688 5.87648437 8.70453125 6.50296875 9.5625 7.1484375 C18.76036546 14.95356624 26.15845232 28.59050337 27.26025391 40.67626953 C27.73579386 51.65011278 27.93683722 62.18235196 23.0390625 72.25 C22.58015625 73.21164062 22.12125 74.17328125 21.6484375 75.1640625 C13.91897924 90.25684678 1.74462952 98.78970206 -14.12109375 104.359375 C-26.20509403 107.16217466 -40.75813646 106.70001132 -51.9609375 101.25 C-52.92257813 100.79109375 -53.88421875 100.3321875 -54.875 99.859375 C-69.95673947 92.13557311 -78.53387692 79.95237876 -84.06640625 64.078125 C-87.48632329 49.44267215 -85.88294958 33.26983294 -78.2109375 20.2890625 C-76.54934502 17.84680803 -74.82320526 15.54138091 -72.9609375 13.25 C-72.33445312 12.41726562 -71.70796875 11.58453125 -71.0625 10.7265625 C-54.23488249 -9.10375256 -21.90682862 -12.94757154 0 0 Z M-61.421875 26.09765625 C-68.14505217 35.49986595 -68.94584911 46.05282056 -67.9609375 57.25 C-65.7647162 68.01942251 -59.1843623 76.38422662 -50.38671875 82.7421875 C-40.41077851 88.94301348 -29.1889132 89.97308289 -17.80859375 87.58984375 C-6.62384645 83.96617387 1.84161302 76.06122995 7.359375 65.79296875 C11.41050101 56.34506299 11.6392523 45.07439536 8.4765625 35.3125 C3.89997856 24.63913815 -4.35007565 16.38908394 -15.0234375 11.8125 C-32.85669213 6.03482564 -49.64786292 12.09249576 -61.421875 26.09765625 Z \" fill=\"#FFFFFF\" transform=\"translate(148.9609375,198.75)\"><\/path><path d=\"M0 0 C5.61 0 11.22 0 17 0 C17 7.41949768 16.4193994 9.5739037 12 15 C10.38951504 16.5361957 8.76384857 18.05660014 7.125 19.5625 C3.59894001 22.93595778 3.59894001 22.93595778 2.4375 27.625 C4.3016423 31.65154737 6.53640084 33.44653953 9.921875 36.2109375 C14.35231511 40.02511338 16.66640348 43.47588476 17.44140625 49.33984375 C17.6712265 56.28634622 17.55516374 62.49009234 13 68 C10.49336318 70.42173461 7.93083016 72.70394426 5.2421875 74.921875 C2.68119792 77.0509375 2.68119792 77.0509375 1 81 C-4.28 81 -9.56 81 -15 81 C-15 72.89829843 -14.78249696 70.77385737 -10 65 C-8.38818944 63.46519521 -6.76257519 61.94478449 -5.125 60.4375 C-1.59894001 57.06404222 -1.59894001 57.06404222 -0.4375 52.375 C-2.3016423 48.34845263 -4.53640084 46.55346047 -7.921875 43.7890625 C-12.35231511 39.97488662 -14.66640348 36.52411524 -15.44140625 30.66015625 C-15.67119392 23.71463861 -15.55593476 17.50843498 -11 12 C-8.46103287 9.54579966 -5.86542176 7.23127861 -3.14453125 4.98046875 C-0.76665692 3.10398078 -0.76665692 3.10398078 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(367,88)\"><\/path><path d=\"M0 0 C5.61 0 11.22 0 17 0 C17 7.41949768 16.4193994 9.5739037 12 15 C10.38951504 16.5361957 8.76384857 18.05660014 7.125 19.5625 C3.59894001 22.93595778 3.59894001 22.93595778 2.4375 27.625 C4.3016423 31.65154737 6.53640084 33.44653953 9.921875 36.2109375 C14.35231511 40.02511338 16.66640348 43.47588476 17.44140625 49.33984375 C17.6712265 56.28634622 17.55516374 62.49009234 13 68 C10.49336318 70.42173461 7.93083016 72.70394426 5.2421875 74.921875 C2.68119792 77.0509375 2.68119792 77.0509375 1 81 C-4.28 81 -9.56 81 -15 81 C-15 72.89829843 -14.78249696 70.77385737 -10 65 C-8.38818944 63.46519521 -6.76257519 61.94478449 -5.125 60.4375 C-1.59894001 57.06404222 -1.59894001 57.06404222 -0.4375 52.375 C-2.3016423 48.34845263 -4.53640084 46.55346047 -7.921875 43.7890625 C-12.35231511 39.97488662 -14.66640348 36.52411524 -15.44140625 30.66015625 C-15.67119392 23.71463861 -15.55593476 17.50843498 -11 12 C-8.46103287 9.54579966 -5.86542176 7.23127861 -3.14453125 4.98046875 C-0.76665692 3.10398078 -0.76665692 3.10398078 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(327,88)\"><\/path><path d=\"M0 0 C5.61 0 11.22 0 17 0 C17 7.41949768 16.4193994 9.5739037 12 15 C10.38951504 16.5361957 8.76384857 18.05660014 7.125 19.5625 C3.59894001 22.93595778 3.59894001 22.93595778 2.4375 27.625 C4.3016423 31.65154737 6.53640084 33.44653953 9.921875 36.2109375 C14.35231511 40.02511338 16.66640348 43.47588476 17.44140625 49.33984375 C17.6712265 56.28634622 17.55516374 62.49009234 13 68 C10.49336318 70.42173461 7.93083016 72.70394426 5.2421875 74.921875 C2.68119792 77.0509375 2.68119792 77.0509375 1 81 C-4.28 81 -9.56 81 -15 81 C-15 72.89829843 -14.78249696 70.77385737 -10 65 C-8.38818944 63.46519521 -6.76257519 61.94478449 -5.125 60.4375 C-1.59894001 57.06404222 -1.59894001 57.06404222 -0.4375 52.375 C-2.3016423 48.34845263 -4.53640084 46.55346047 -7.921875 43.7890625 C-12.35231511 39.97488662 -14.66640348 36.52411524 -15.44140625 30.66015625 C-15.67119392 23.71463861 -15.55593476 17.50843498 -11 12 C-8.46103287 9.54579966 -5.86542176 7.23127861 -3.14453125 4.98046875 C-0.76665692 3.10398078 -0.76665692 3.10398078 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(287,88)\"><\/path><path d=\"M0 0 C5.28 0 10.56 0 16 0 C16 5.28 16 10.56 16 16 C10.72 16 5.44 16 0 16 C0 10.72 0 5.44 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(312,336)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMassage de relaxation asiatique traditionnelle\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUne douce, fluide <b>corps entier<\/b> Massage qui aide \u00e0 d\u00e9tendre compl\u00e8tement votre corps. Id\u00e9al en cas de stress ou de fatigue.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f01489 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7f01489\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-f83ac15 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f83ac15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/traditionele-aziatische-ontspanningsmassage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apprendre plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f11ad9 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4f11ad9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5193cc elementor-widget elementor-widget-image\" data-id=\"d5193cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/asian-young-woman-feeling-happy-and-relax-during-b-2023-11-27-05-23-17-utc-200x200-1.jpg\" class=\"attachment-full size-full wp-image-987815\" alt=\"\" srcset=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/asian-young-woman-feeling-happy-and-relax-during-b-2023-11-27-05-23-17-utc-200x200-1.jpg 200w, https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/asian-young-woman-feeling-happy-and-relax-during-b-2023-11-27-05-23-17-utc-200x200-1-150x150.jpg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc15cec elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fc15cec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\"><path d=\"M0 0 C9.9 0 19.8 0 30 0 C30 0.99 30 1.98 30 3 C27.03 3 24.06 3 21 3 C21.495 8.445 21.495 8.445 22 14 C24.64 14.33 27.28 14.66 30 15 C30 15.99 30 16.98 30 18 C28.37536158 18.05395478 26.75021459 18.09277195 25.125 18.125 C23.76761719 18.15980469 23.76761719 18.15980469 22.3828125 18.1953125 C20 18 20 18 18 16 C17.72759327 12.98173347 17.91324875 10.03629378 18 7 C13.38 7 8.76 7 4 7 C3.67 8.98 3.34 10.96 3 13 C1 15 1 15 -2.0390625 15.1953125 C-3.22242188 15.17210937 -4.40578125 15.14890625 -5.625 15.125 C-6.81351563 15.10695313 -8.00203125 15.08890625 -9.2265625 15.0703125 C-10.14179688 15.04710937 -11.05703125 15.02390625 -12 15 C-12 13.68 -12 12.36 -12 11 C-7.545 10.505 -7.545 10.505 -3 10 C-1.53173403 6.57404607 -0.74613857 3.73069283 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(15,24)\"><\/path><path d=\"M0 0 C5.05074018 2.16460293 7.69437289 5.85238062 10.5 10.5 C10.5 11.16 10.5 11.82 10.5 12.5 C6.87 12.5 3.24 12.5 -0.5 12.5 C-1.16 11.18 -1.82 9.86 -2.5 8.5 C-3.015625 9.16 -3.53125 9.82 -4.0625 10.5 C-7.29995755 13.15637543 -9.42552281 12.81342132 -13.5 12.5 C-10.54534014 6.7644838 -6.65900011 0.95128573 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(31.5,9.5)\"><\/path><path d=\"M0 0 C2.5 0.125 2.5 0.125 3.5 1.125 C3.625 3.625 3.625 3.625 3.5 6.125 C2.5 7.125 2.5 7.125 0 7.25 C-2.5 7.125 -2.5 7.125 -3.5 6.125 C-3.625 3.625 -3.625 3.625 -3.5 1.125 C-2.5 0.125 -2.5 0.125 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(9.5,23.875)\"><\/path><path d=\"M0 0 C2.5 0.125 2.5 0.125 3.5 1.125 C3.625 3.625 3.625 3.625 3.5 6.125 C2.5 7.125 2.5 7.125 0 7.25 C-2.5 7.125 -2.5 7.125 -3.5 6.125 C-3.625 3.625 -3.625 3.625 -3.5 1.125 C-2.5 0.125 -2.5 0.125 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(23.5,4.875)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDeep Tissue Massage\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUne plus intensive <b>corps entier<\/b> massage, aussi parfois appel\u00e9e massage sportif, ciblant les couches musculaires plus profondes. Aide en cas de muscles raides et de tensions accumul\u00e9es.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fbd6a0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2fbd6a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-2cbf79f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2cbf79f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/deep-tissue-massage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apprendre plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a35d9b4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a35d9b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8643721 elementor-widget elementor-widget-image\" data-id=\"8643721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Head-Neck-Shoulder-200x200-1.png\" class=\"attachment-full size-full wp-image-987813\" alt=\"\" srcset=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Head-Neck-Shoulder-200x200-1.png 200w, https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Head-Neck-Shoulder-200x200-1-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e5034b elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7e5034b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 512 512\"><path d=\"M0 0 C15.57465534 12.10398006 25.23499518 28.5968573 28.9296875 47.8671875 C29.43283195 52.77779473 29.46797976 57.62953999 29.43089294 62.56285095 C29.43479769 63.97665783 29.44044745 65.39046074 29.44766384 66.80425459 C29.46226707 70.6429996 29.45232901 74.48132807 29.43792713 78.32005894 C29.42673466 82.47747078 29.43878674 86.63482807 29.44776917 90.79223633 C29.46164517 98.91634516 29.45418859 107.04029774 29.43909358 115.16439902 C29.42217425 124.63288263 29.42545094 134.10132796 29.42918766 143.56982202 C29.43505532 160.46332754 29.42093468 177.35675831 29.39624023 194.25024414 C29.37229601 210.63243405 29.36524774 227.01452424 29.37573242 243.39672852 C29.38714412 261.25926682 29.38907063 279.12175911 29.37463433 296.98429686 C29.37310854 298.88892559 29.37158819 300.79355432 29.37007332 302.69818306 C29.3693155 303.63519415 29.36855769 304.57220524 29.36777691 305.5376106 C29.36303813 312.13441946 29.36488245 318.73120773 29.36913872 325.32801628 C29.3740672 333.36397386 29.3680721 341.39983723 29.34824442 349.43577325 C29.33838093 353.53402808 29.33325729 357.63213953 29.34113693 361.73040199 C29.34820557 365.48360561 29.34136174 369.23652015 29.3235333 372.98968572 C29.31758833 374.98626445 29.32630149 376.98287032 29.33557981 378.97943634 C29.28799348 385.71439255 28.67462732 390.71521581 25.9296875 396.8671875 C26.07723994 401.44131317 28.51159215 405.20768078 30.6171875 409.1796875 C45.6048869 438.49188397 45.9296875 464.1950853 45.9296875 497.8671875 C-68.9103125 497.8671875 -183.7503125 497.8671875 -302.0703125 497.8671875 C-302.0703125 443.53625624 -302.0703125 443.53625624 -295.6328125 425.6796875 C-295.34599609 424.83083984 -295.05917969 423.98199219 -294.76367188 423.10742188 C-292.9218251 417.78698699 -290.68618583 412.85171976 -288.0703125 407.8671875 C-288.69284912 407.57908203 -289.31538574 407.29097656 -289.95678711 406.99414062 C-292.6697113 405.547582 -293.8621458 403.87068046 -295.6328125 401.3671875 C-296.21160156 400.573125 -296.79039062 399.7790625 -297.38671875 398.9609375 C-301.47119895 391.45534976 -302.51314251 383.97044211 -302.4445343 375.53363037 C-302.44850871 374.54266082 -302.45248311 373.55169127 -302.45657796 372.53069234 C-302.46614185 369.23613241 -302.45441839 365.94200828 -302.44262695 362.64746094 C-302.44505692 360.27464132 -302.44877823 357.90182273 -302.45368958 355.52900696 C-302.46307605 349.10112322 -302.45369074 342.67339237 -302.44035745 336.24552059 C-302.42887539 330.18956281 -302.432659 324.13360521 -302.43455996 318.07763997 C-302.43774519 306.07207934 -302.42611101 294.06657815 -302.40649414 282.06103516 C-302.38750907 270.43894641 -302.38040276 258.81692736 -302.38598633 247.19482422 C-302.39206054 234.5141155 -302.39183577 221.83343738 -302.3805005 209.15273118 C-302.37929333 207.7972579 -302.37808734 206.44178462 -302.37688255 205.08631134 C-302.37627901 204.41955239 -302.37567548 203.75279344 -302.37505365 203.06582968 C-302.3711924 198.39200343 -302.37162163 193.7181925 -302.3734684 189.04436493 C-302.37536107 182.73731101 -302.36717242 176.43034571 -302.351408 170.123312 C-302.34718845 167.81678064 -302.34629879 165.51024026 -302.34909821 163.20370674 C-302.36105615 151.5825719 -302.27688274 140.31797779 -300.0703125 128.8671875 C-299.9360703 128.15236584 -299.8018281 127.43754417 -299.66351795 126.70106125 C-294.99988755 104.13736333 -282.94665531 85.1392024 -267.0703125 68.8671875 C-266.49023438 68.22523437 -265.91015625 67.58328125 -265.3125 66.921875 C-247.86033148 48.06651705 -219.20501623 36.69540613 -194.0703125 34.8671875 C-188.59755994 34.72210349 -183.12649222 34.72614181 -177.65234375 34.734375 C-176.06532273 34.73370017 -174.4783018 34.73272865 -172.89128113 34.73147583 C-169.58058682 34.7300086 -166.26991965 34.73212278 -162.95922852 34.73681641 C-158.72602854 34.74252716 -154.49289179 34.73922 -150.2596941 34.73324394 C-146.98853583 34.72962391 -143.71739247 34.73078331 -140.44623375 34.73337173 C-138.88539307 34.73403628 -137.32455101 34.73322916 -135.76371193 34.73089218 C-133.58177748 34.72834037 -131.39994451 34.73224111 -129.21801758 34.73779297 C-127.97941483 34.73858856 -126.74081207 34.73938416 -125.4646759 34.74020386 C-122.24478947 34.86066029 -119.23071655 35.25830388 -116.0703125 35.8671875 C-115.92335938 35.33351562 -115.77640625 34.79984375 -115.625 34.25 C-110.76645478 18.11069463 -99.01382173 3.95503707 -84.37109375 -4.26171875 C-56.62907779 -19.14510987 -25.9956435 -18.05804243 0 0 Z M-90.13671875 24.23046875 C-95.97355686 31.27505051 -95.97355686 31.27505051 -98.0703125 39.8671875 C-97.02875 40.2075 -95.9871875 40.5478125 -94.9140625 40.8984375 C-58.82071757 52.97626701 -33.77240576 75.25109121 -16.0703125 108.8671875 C-3.58702037 102.05811906 4.95692119 91.37861904 9.31640625 77.83203125 C13.93200845 61.80191075 12.6229215 46.53419584 4.7265625 31.71875 C1.67936098 26.88297367 -2.01224586 22.86956883 -6.0703125 18.8671875 C-6.70839844 18.21878906 -7.34648437 17.57039063 -8.00390625 16.90234375 C-18.21227433 7.20333291 -31.6812966 2.89331431 -45.5703125 2.4921875 C-63.62762387 3.03477498 -78.30945779 10.70401718 -90.13671875 24.23046875 Z M-257.0703125 83.8671875 C-257.81023437 84.60710937 -258.55015625 85.34703125 -259.3125 86.109375 C-275.51775493 103.3235174 -284.22295656 127.00173089 -284.5703125 150.4296875 C-284.58892334 151.23825195 -284.60753418 152.04681641 -284.62670898 152.87988281 C-284.53233263 161.76042255 -280.98342995 168.66114281 -274.98828125 175.078125 C-269.14885134 180.52508813 -262.51398797 184.0192902 -254.4140625 183.79296875 C-249.58314823 183.43605565 -249.58314823 183.43605565 -245.0703125 181.8671875 C-245.0703125 181.2071875 -245.0703125 180.5471875 -245.0703125 179.8671875 C-246.36737857 178.97845704 -247.71083615 178.15715349 -249.0703125 177.3671875 C-254.65689966 173.77769528 -258.21433023 169.19955938 -262.0703125 163.8671875 C-262.53953125 163.26132813 -263.00875 162.65546875 -263.4921875 162.03125 C-266.0915809 158.52384932 -266.0915809 158.52384932 -266.0078125 155.9375 C-264.60326421 152.83578919 -262.39241982 151.84132061 -259.5078125 150.1171875 C-258.49589844 149.50359375 -257.48398437 148.89 -256.44140625 148.2578125 C-255.65894531 147.79890625 -254.87648438 147.34 -254.0703125 146.8671875 C-250.97839464 149.761604 -248.75302474 152.76455872 -246.4453125 156.3046875 C-242.45569372 161.83104833 -238.66253214 164.98227145 -232.0703125 166.8671875 C-225.64085825 167.83785249 -220.78626161 166.84942182 -215.0703125 163.8671875 C-215.0703125 163.2071875 -215.0703125 162.5471875 -215.0703125 161.8671875 C-216.88948831 160.29741402 -216.88948831 160.29741402 -219.1953125 158.6796875 C-227.07472802 152.69281605 -232.86764338 145.70286844 -235.0703125 135.8671875 C-234.42964844 135.74601562 -233.78898437 135.62484375 -233.12890625 135.5 C-228.02102317 134.51039523 -223.04780981 133.38207799 -218.0703125 131.8671875 C-217.96589844 132.6096875 -217.86148438 133.3521875 -217.75390625 134.1171875 C-216.3874939 139.61406917 -212.25175332 143.48639992 -207.55859375 146.45703125 C-201.51169212 149.57538859 -196.3456356 150.96246739 -189.52734375 151.04296875 C-172.84031556 151.3723429 -157.72663888 152.78949602 -142.13671875 159.1328125 C-139.96468368 160.03462205 -139.96468368 160.03462205 -137.0703125 159.8671875 C-137.78991164 147.3941357 -143.33524389 138.49287243 -152.0703125 129.8671875 C-153.13572266 128.73796875 -153.13572266 128.73796875 -154.22265625 127.5859375 C-155.89379528 125.64015285 -155.89379528 125.64015285 -158.0703125 125.8671875 C-155.1003125 121.2471875 -152.1303125 116.6271875 -149.0703125 111.8671875 C-137.28961061 116.57946826 -130.38376726 127.15818868 -125.12890625 138.33984375 C-120.63312295 149.07331901 -120.00983392 160.38883329 -119.0703125 171.8671875 C-118.23628906 171.5784375 -117.40226563 171.2896875 -116.54296875 170.9921875 C-105.82543304 167.45650562 -97.65049214 166.35480071 -87.0703125 170.8671875 C-79.78903039 174.90228522 -75.04848013 181.00983754 -71.9296875 188.66796875 C-69.29406842 198.47965979 -70.09253964 209.96716952 -75.0703125 218.8671875 C-75.95906436 220.01275069 -76.86565902 221.14458988 -77.78515625 222.265625 C-88.49275591 235.80400937 -87.22784846 249.39456032 -86.0703125 265.8671875 C-55.83384583 246.87641104 -32.10595793 223.44586375 -23.6953125 187.8671875 C-17.31981967 158.90238504 -22.27195416 129.0538337 -38.0703125 103.8671875 C-40.82674441 99.66809281 -43.86860087 95.73615602 -47.0703125 91.8671875 C-47.75480469 91.01898438 -48.43929687 90.17078125 -49.14453125 89.296875 C-61.12978027 75.16269963 -77.27827418 64.76859566 -94.6328125 58.4921875 C-95.25583252 58.2655542 -95.87885254 58.0389209 -96.52075195 57.80541992 C-109.64444055 53.3876597 -122.46954911 52.40076634 -136.18359375 52.43359375 C-137.89023543 52.42901455 -139.59687528 52.42370393 -141.30351257 52.41770935 C-144.85761059 52.40884586 -148.41148312 52.41112245 -151.96557617 52.42114258 C-156.46673664 52.43261115 -160.96711001 52.41241829 -165.4681673 52.38322544 C-168.98690033 52.36466689 -172.50545161 52.36519467 -176.02422142 52.37086296 C-177.68121632 52.37101385 -179.33822546 52.36516718 -180.9951725 52.35257149 C-210.79965066 52.15786763 -236.04422912 62.84110412 -257.0703125 83.8671875 Z M10.9296875 108.8671875 C9.43257036 110.3703536 7.95764702 111.89564173 6.4921875 113.4296875 C1.70230071 118.28869243 -3.34131072 122.18599912 -9.0703125 125.8671875 C-8.7815625 127.10726562 -8.4928125 128.34734375 -8.1953125 129.625 C-3.32240143 152.17305203 -2.88711889 175.54533895 -9.0703125 197.8671875 C-9.39773438 199.1253125 -9.72515625 200.3834375 -10.0625 201.6796875 C-14.83607613 217.84712782 -24.09963889 238.52750705 -37.76318359 249.18798828 C-39.59401277 250.66943467 -40.80862566 251.87158747 -42.0703125 253.8671875 C-42.24476863 256.23742413 -42.24476863 256.23742413 -41.8605957 258.82543945 C-41.74492752 259.80449753 -41.62925934 260.7835556 -41.51008606 261.7922821 C-40.78956572 266.83017449 -39.9522513 271.83735484 -39.0390625 276.84375 C-38.84308472 277.93561615 -38.64710693 279.0274823 -38.44519043 280.1524353 C-38.03396393 282.43683821 -37.62040262 284.72082197 -37.20458984 287.00439453 C-36.56596542 290.51609144 -35.93680326 294.02939539 -35.30859375 297.54296875 C-34.9068077 299.76832993 -34.50448366 301.99359406 -34.1015625 304.21875 C-33.81871399 305.79978012 -33.81871399 305.79978012 -33.53015137 307.41275024 C-33.35326782 308.3782077 -33.17638428 309.34366516 -32.99414062 310.33837891 C-32.7621698 311.61764755 -32.7621698 311.61764755 -32.5255127 312.92276001 C-32.25193463 314.86133622 -32.25193463 314.86133622 -31.0703125 315.8671875 C-29.36563558 315.96259852 -27.66032869 316.05158903 -25.95385742 316.10620117 C-11.67223069 316.59810753 0.03728524 320.93891933 11.9296875 328.8671875 C11.9296875 256.2671875 11.9296875 183.6671875 11.9296875 108.8671875 C11.5996875 108.8671875 11.2696875 108.8671875 10.9296875 108.8671875 Z M-200.0703125 173.8671875 C-205.2074748 177.98811987 -210.29144822 180.90214817 -216.7578125 182.2421875 C-222.37961401 183.52059152 -224.41802422 186.1794211 -227.9140625 190.578125 C-232.88349103 195.85364151 -239.80582035 198.44180613 -246.77172852 199.94165039 C-247.57796158 200.11652481 -248.38419464 200.29139923 -249.21485901 200.47157288 C-249.82715866 200.6021257 -250.43945831 200.73267853 -251.0703125 200.8671875 C-251.16372785 208.70909861 -251.234435 216.55087502 -251.27756119 224.39320564 C-251.2982784 228.03626534 -251.32629773 231.67893946 -251.37207031 235.32177734 C-251.41610497 238.84909631 -251.43956824 242.37604868 -251.44982147 245.90362167 C-251.46061553 247.87858949 -251.49174504 249.85341348 -251.52349854 251.82815552 C-251.52622987 263.04039429 -249.29988608 272.91472033 -244.0703125 282.8671875 C-227.9284125 283.46258545 -213.38694349 281.21145289 -201.0703125 269.8671875 C-197.61829611 271.34440172 -195.42069314 273.30512751 -192.8203125 275.9921875 C-192.11390625 276.71664062 -191.4075 277.44109375 -190.6796875 278.1875 C-190.14859375 278.74179687 -189.6175 279.29609375 -189.0703125 279.8671875 C-192.21602567 287.63794923 -201.90702763 291.65747358 -209.1953125 294.8046875 C-215.64347435 297.18770384 -222.33951062 298.54550277 -229.0703125 299.8671875 C-219.71500802 310.09955178 -206.04475355 315.047258 -192.3515625 316.0703125 C-175.85491523 316.34834588 -160.07365427 311.3797 -147.5703125 300.4296875 C-143.15764602 296.13668655 -139.04646361 291.56526549 -135.0703125 286.8671875 C-130.23491154 289.47830402 -126.19927349 292.24175833 -122.0703125 295.8671875 C-127.43033698 307.40174998 -138.47869106 317.15244148 -149.8203125 322.7421875 C-153.90623211 325.41375032 -154.53165547 327.39865092 -156.0078125 331.9921875 C-159.97605644 343.1464623 -166.57512396 351.13555452 -177.0703125 356.8671875 C-184.73194609 360.28370855 -192.92800064 361.73353899 -201.10839844 363.35913086 C-207.33810021 364.62528448 -213.20385189 366.38877268 -219.0703125 368.8671875 C-219.0290625 370.1665625 -218.9878125 371.4659375 -218.9453125 372.8046875 C-218.9946006 383.30305301 -222.12632424 392.22369332 -229.5703125 399.8046875 C-239.33762825 407.90878754 -252.27530423 414.21342238 -265.0078125 414.6796875 C-270.31154553 414.99856039 -270.31154553 414.99856039 -274.2109375 418.2578125 C-275.89963918 421.72050383 -277.03896552 425.17346388 -278.0703125 428.8671875 C-278.53711819 430.33348706 -279.00862662 431.79829624 -279.484375 433.26171875 C-282.26983969 442.07646834 -284.21098889 450.34041086 -284.16796875 459.67578125 C-284.16547119 460.79525146 -284.16297363 461.91472168 -284.16040039 463.06811523 C-284.15129639 464.46618408 -284.14219238 465.86425293 -284.1328125 467.3046875 C-284.1121875 471.7803125 -284.0915625 476.2559375 -284.0703125 480.8671875 C-268.2303125 480.8671875 -252.3903125 480.8671875 -236.0703125 480.8671875 C-235.86066677 466.46321041 -235.86066677 466.46321041 -235.68237305 452.05883789 C-235.65004919 450.23581958 -235.61667073 448.41281953 -235.58203125 446.58984375 C-235.57578735 445.66425659 -235.56954346 444.73866943 -235.56311035 443.78503418 C-235.36634107 434.78015639 -233.6336305 427.28133918 -227.0703125 420.8671875 C-221.04054895 416.639578 -216.21525633 415.74355306 -208.96148682 415.72674561 C-208.24500843 415.72377448 -207.52853004 415.72080336 -206.79034019 415.7177422 C-204.3891863 415.70906968 -201.98808236 415.70754818 -199.58691406 415.70605469 C-197.86533502 415.70142547 -196.143757 415.69640067 -194.42218018 415.69100952 C-189.74434351 415.67789305 -185.06652119 415.67144197 -180.38866901 415.66699886 C-177.46520355 415.66406678 -174.541742 415.6599617 -171.6182785 415.65549469 C-162.46874899 415.64182142 -153.31922844 415.63215407 -144.16968942 415.6282928 C-133.6129785 415.62381305 -123.05639712 415.60626826 -112.49972558 415.5772922 C-104.33652744 415.5556647 -96.17336571 415.54558794 -88.01013923 415.54425168 C-83.13616693 415.54320437 -78.26231643 415.53731239 -73.38837433 415.51943207 C-68.80173638 415.50293304 -64.21531156 415.50080478 -59.62865448 415.50957108 C-57.94849577 415.51034048 -56.26832552 415.50601146 -54.5881958 415.49611282 C-44.89847901 415.44238897 -37.15396928 415.44549544 -28.8203125 421.0546875 C-23.48866307 426.50751078 -21.01414878 432.86637102 -20.86499023 440.45214844 C-20.84480835 441.36528809 -20.82462646 442.27842773 -20.80383301 443.21923828 C-20.78735718 444.17040527 -20.77088135 445.12157227 -20.75390625 446.1015625 C-20.73525513 446.98215332 -20.716604 447.86274414 -20.6973877 448.77001953 C-20.62920664 452.05230901 -20.56898356 455.3347599 -20.5078125 458.6171875 C-20.3634375 465.9596875 -20.2190625 473.3021875 -20.0703125 480.8671875 C-4.2303125 480.8671875 11.6096875 480.8671875 27.9296875 480.8671875 C27.9296875 454.76929762 25.15467886 434.00263403 11.9296875 411.8671875 C8.96829308 412.43296165 6.14600365 413.09299471 3.2421875 413.9296875 C-11.44609354 417.51954723 -24.90365438 411.29433963 -37.39111328 403.94628906 C-44.92595699 399.10418247 -49.04975999 392.73488218 -52.4453125 384.5546875 C-53.86977147 376.15037959 -53.62201186 368.0007292 -51.0703125 359.8671875 C-56.0154856 357.9038293 -60.8480941 356.35606882 -66.02246094 355.13134766 C-74.17278874 353.19149737 -81.38234807 351.14440943 -88.0703125 345.8671875 C-89.029375 345.11695313 -89.029375 345.11695313 -90.0078125 344.3515625 C-98.13600988 337.13428379 -102.21052934 326.34002869 -103.2898407 315.70381927 C-103.40957354 313.50181504 -103.47644249 311.30541148 -103.51953125 309.10058594 C-103.55370148 307.86174149 -103.55370148 307.86174149 -103.58856201 306.59786987 C-103.80962341 297.98177698 -103.90466486 289.36246761 -103.99023438 280.74414062 C-104.0346028 276.67924836 -104.11787326 272.61808298 -104.23632812 268.5546875 C-105.43571065 226.44532344 -105.43571065 226.44532344 -90.53128052 210.60083008 C-87.98098556 207.57454895 -87.14710531 204.4030437 -86.953125 200.5234375 C-87.6539289 194.28402211 -89.35463623 190.19491002 -94.2578125 185.9921875 C-98.18596829 184.42092518 -101.91008421 183.99961937 -106.0703125 184.8671875 C-110.48984835 187.53962619 -114.00587409 190.57645505 -117.6171875 194.25390625 C-118.3631015 195.0076226 -118.3631015 195.0076226 -119.12408447 195.77656555 C-120.69439567 197.36452677 -122.25777264 198.95908185 -123.8203125 200.5546875 C-125.39803963 202.16006452 -126.97723235 203.76393065 -128.55938721 205.36494446 C-129.9852849 206.8086375 -131.40634361 208.2571051 -132.82714844 209.70581055 C-135.0703125 211.8671875 -135.0703125 211.8671875 -137.0703125 212.8671875 C-137.02841797 211.92399658 -136.98652344 210.98080566 -136.94335938 210.0090332 C-136.80667231 206.49561343 -136.70659048 202.98502975 -136.63085938 199.4699707 C-136.59071943 197.95161271 -136.5361892 196.43356228 -136.46679688 194.91625977 C-135.74411613 186.4082101 -135.74411613 186.4082101 -138.65820312 178.82421875 C-140.76350885 177.46778016 -142.69326199 176.64069345 -145.0703125 175.8671875 C-146.153125 175.37992188 -147.2359375 174.89265625 -148.3515625 174.390625 C-160.73345675 169.97281322 -172.65982097 167.64422976 -185.7578125 167.3046875 C-186.60746582 167.26561279 -187.45711914 167.22653809 -188.33251953 167.1862793 C-194.54729376 167.15950758 -196.40540381 168.63525851 -200.0703125 173.8671875 Z M-284.0703125 190.8671875 C-284.0703125 236.4071875 -284.0703125 281.9471875 -284.0703125 328.8671875 C-280.6053125 326.8871875 -280.6053125 326.8871875 -277.0703125 324.8671875 C-264.16806609 317.82653606 -253.5055618 316.49696876 -239.0703125 315.8671875 C-239.81667969 315.1246875 -240.56304687 314.3821875 -241.33203125 313.6171875 C-260.68045415 294.18596107 -268.24183353 273.30803012 -268.484375 246.1328125 C-268.50313932 244.75989691 -268.52271639 243.38699221 -268.5430603 242.01409912 C-268.59383288 238.44358826 -268.63374761 234.87304022 -268.67120361 231.30236816 C-268.71159258 227.64159369 -268.76252346 223.98096642 -268.8125 220.3203125 C-268.9086071 213.16937384 -268.99223751 206.01834914 -269.0703125 198.8671875 C-274.0203125 196.2271875 -278.9703125 193.5871875 -284.0703125 190.8671875 Z M-60.0703125 268.8671875 C-62.03699857 269.84385081 -62.03699857 269.84385081 -64.01953125 271.40234375 C-64.78587891 271.96501953 -65.55222656 272.52769531 -66.34179688 273.10742188 C-67.13908203 273.70876953 -67.93636719 274.31011719 -68.7578125 274.9296875 C-69.53576172 275.50396484 -70.31371094 276.07824219 -71.11523438 276.66992188 C-72.68109857 277.82832182 -74.23418657 279.00418672 -75.77416992 280.19677734 C-78.0703125 281.8671875 -78.0703125 281.8671875 -80.4074707 283.10400391 C-82.87747833 284.50405051 -84.37549881 285.57539629 -86.0703125 287.8671875 C-87.03735975 292.27873301 -87.09678937 296.5304107 -86.94848633 301.01513672 C-86.88335109 303.09994863 -86.88682198 305.17609487 -86.90039062 307.26171875 C-86.83850111 316.25874792 -85.63465045 324.08452094 -79.2277832 330.79785156 C-75.72251077 333.99613278 -72.30867006 336.56211273 -67.51953125 337.21484375 C-65.00592531 337.09067128 -65.00592531 337.09067128 -63.40234375 335.36328125 C-62.90089844 334.68394531 -62.39945313 334.00460937 -61.8828125 333.3046875 C-59.1869613 329.90420307 -56.4223057 327.51968495 -52.83203125 325.08984375 C-51.93830811 324.48019775 -51.04458496 323.87055176 -50.1237793 323.24243164 C-49.44613525 322.78860107 -48.76849121 322.33477051 -48.0703125 321.8671875 C-50.92568427 304.5058221 -53.85157516 287.16565297 -57.0703125 269.8671875 C-58.0603125 269.5371875 -59.0503125 269.2071875 -60.0703125 268.8671875 Z M-203.0703125 331.8671875 C-201.0903125 334.5071875 -199.1103125 337.1471875 -197.0703125 339.8671875 C-196.0803125 341.1871875 -195.0903125 342.5071875 -194.0703125 343.8671875 C-187.58602521 343.59126038 -182.9488118 341.14060161 -178.0703125 336.8671875 C-177.0803125 335.2171875 -176.0903125 333.5671875 -175.0703125 331.8671875 C-184.3103125 331.8671875 -193.5503125 331.8671875 -203.0703125 331.8671875 Z M-273.8515625 343.4609375 C-282.26337747 352.55943124 -284.27154674 362.31449779 -284.3828125 374.2421875 C-284.41181641 375.27085937 -284.44082031 376.29953125 -284.47070312 377.359375 C-284.52125522 383.39451739 -284.25433806 387.15734186 -280.0703125 391.8671875 C-276.37023472 395.59382086 -272.91072432 398.05242132 -267.6328125 398.5546875 C-261.3605888 398.52969856 -256.63178054 396.09213753 -251.1953125 393.2421875 C-250.37490479 392.81639404 -249.55449707 392.39060059 -248.70922852 391.9519043 C-242.85014326 388.72529229 -238.2676796 385.4592888 -236.0703125 378.8671875 C-235.29743096 372.44340162 -236.12045817 367.10330563 -240.0703125 361.8671875 C-242.30888114 359.89226184 -244.5114823 358.44185224 -247.0703125 356.8671875 C-246.6371875 355.95195312 -246.2040625 355.03671875 -245.7578125 354.09375 C-245.2009375 352.90523438 -244.6440625 351.71671875 -244.0703125 350.4921875 C-243.5134375 349.30882812 -242.9565625 348.12546875 -242.3828125 346.90625 C-240.93815209 344.11290175 -240.93815209 344.11290175 -241.0703125 341.8671875 C-234.46276015 344.29445163 -230.0116012 347.9258988 -225.0703125 352.8671875 C-221.1103125 351.5471875 -217.1503125 350.2271875 -213.0703125 348.8671875 C-219.02675966 340.59434422 -227.39588864 336.67388813 -237.0703125 333.8671875 C-250.92908233 331.65974273 -263.17861671 333.91145969 -273.8515625 343.4609375 Z M-47.0703125 341.8671875 C-42.31246914 345.13505908 -42.31246914 345.13505908 -36.76953125 345.515625 C-33.91585994 344.83008312 -31.08610865 344.08843222 -28.2578125 343.3046875 C-26.5459375 342.8303125 -24.8340625 342.3559375 -23.0703125 341.8671875 C-21.4203125 347.1471875 -19.7703125 352.4271875 -18.0703125 357.8671875 C-19.7821875 358.2590625 -21.4940625 358.6509375 -23.2578125 359.0546875 C-29.58263385 360.79218656 -32.32361795 363.24714567 -35.9453125 368.6796875 C-37.39417426 372.78479582 -37.2852332 375.71482155 -36.0703125 379.8671875 C-30.96722659 389.50634978 -21.03198076 394.44854839 -11.0703125 397.8671875 C-5.96658931 398.87983099 -1.84639538 398.554291 2.8046875 396.1796875 C7.43061259 392.75650293 10.2238387 389.36381142 11.9296875 383.8671875 C12.24547578 380.6351112 12.26316771 377.42532642 12.2421875 374.1796875 C12.23654785 373.28209717 12.2309082 372.38450684 12.22509766 371.4597168 C12.01331638 359.92392751 9.00056293 351.47334442 1.11328125 342.890625 C-5.81101899 336.3160369 -15.20622519 332.41672106 -24.8515625 332.5859375 C-33.18572448 333.64238057 -40.64732588 336.48980336 -47.0703125 341.8671875 Z M-217.0703125 434.8671875 C-223.92920778 448.58497806 -218.0703125 465.53023141 -218.0703125 480.8671875 C-158.6703125 480.8671875 -99.2703125 480.8671875 -38.0703125 480.8671875 C-38.0703125 466.3471875 -38.0703125 451.8271875 -38.0703125 436.8671875 C-43.02173921 431.91576079 -45.01904305 431.74310369 -51.69270325 431.72674561 C-52.36890282 431.72377448 -53.04510239 431.72080336 -53.74179286 431.7177422 C-56.01252607 431.70905567 -58.28320656 431.707547 -60.55395508 431.70605469 C-62.18011081 431.70142648 -63.80626545 431.69640182 -65.43241882 431.69100952 C-69.85399022 431.67788375 -74.27554642 431.67144022 -78.69713426 431.66699886 C-81.459267 431.66406842 -84.22139558 431.65996366 -86.98352623 431.65549469 C-95.62474798 431.64181928 -104.26596023 431.63215284 -112.90719205 431.6282928 C-122.88380107 431.62381182 -132.86027309 431.6062623 -142.83684045 431.5772922 C-150.54733715 431.5556792 -158.2577953 431.54558872 -165.96832198 431.54425168 C-170.57396979 431.54320338 -175.17948882 431.53729018 -179.78510475 431.51943207 C-184.11810732 431.50295798 -188.45088422 431.50079263 -192.78390694 431.50957108 C-194.37298944 431.51034181 -195.96208405 431.50599395 -197.55113602 431.49611282 C-199.72334935 431.48339915 -201.89476275 431.48926625 -204.06697083 431.49969482 C-205.28168469 431.49822826 -206.49639856 431.4967617 -207.74792194 431.4952507 C-211.46649456 431.91153951 -213.88897908 432.92547224 -217.0703125 434.8671875 Z \" fill=\"#FFFFFF\" transform=\"translate(384.0703125,14.1328125)\"><\/path><path d=\"M0 0 C2.35358897 1.15659201 4.61004287 2.35806864 6.875 3.6875 C10.59039046 5.24796399 12.18777997 5.21666597 16 4 C18.82865928 2.0554473 18.82865928 2.0554473 21 0 C24.58402695 1.53248049 27.02850134 3.6674601 29.8125 6.375 C31.02873047 7.53128906 31.02873047 7.53128906 32.26953125 8.7109375 C34 11 34 11 34.0234375 13.09375 C32.68014817 15.59575456 31.19909118 16.59790146 28.8125 18.125 C28.05582031 18.62257812 27.29914063 19.12015625 26.51953125 19.6328125 C19.06867575 23.67591239 10.61397604 24.48580418 2.40234375 22.3125 C-2.8421124 20.15354721 -6.94012672 16.91627648 -11 13 C-9.46356148 9.31930113 -7.21849055 7.01224796 -4.375 4.25 C-3.55773437 3.45078125 -2.74046875 2.6515625 -1.8984375 1.828125 C-0.95871094 0.92320312 -0.95871094 0.92320312 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(170,225)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t Massage du dos, du cou et des \u00e9paules\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tParfait pour ceux qui retiennent quotidiennement beaucoup de tension dans le haut du dos, par exemple \u00e0 cause d'un travail de bureau ou du stress.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f90c8e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8f90c8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-fe00061 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"fe00061\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/rug-nek-schoudermassage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apprendre plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0bca472 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"0bca472\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a7c7b40 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a7c7b40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1b148f elementor-widget elementor-widget-image\" data-id=\"d1b148f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Foot-Massage-200x200-2.png\" class=\"attachment-full size-full wp-image-987812\" alt=\"\" srcset=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Foot-Massage-200x200-2.png 200w, https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Foot-Massage-200x200-2-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5afccc5 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5afccc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 512 512\"><path d=\"M0 0 C8.9888442 5.37841816 12.79767841 14.15302945 16.6875 23.5 C18.00234375 22.77103516 18.00234375 22.77103516 19.34375 22.02734375 C24.20197004 19.80822688 28.44023548 19.80297531 33.6875 20.5 C40.44434208 23.75329434 44.85642392 29.6458158 47.6875 36.5 C47.6875 37.82 47.6875 39.14 47.6875 40.5 C48.30625 40.005 48.925 39.51 49.5625 39 C53.98345481 36.87794169 57.86394844 36.81092121 62.6875 37.5 C67.57310295 39.85232735 70.30377054 42.64740788 72.6875 47.5 C73.59159467 51.80986038 74.19423875 56.12555156 74.6875 60.5 C75.739375 60.438125 76.79125 60.37625 77.875 60.3125 C81.98916142 60.51483581 83.52858005 60.93871355 86.6875 63.5 C91.05162316 68.47025138 91.4363129 73.14496631 91.6875 79.5 C92.76 79.891875 93.8325 80.28375 94.9375 80.6875 C98.59245216 82.24862329 100.49635755 84.12901161 102.6875 87.5 C104.74191944 93.66325833 104.07955548 99.50025853 101.734375 105.48046875 C100.6875 107.5 100.6875 107.5 98.4453125 110.32421875 C96.30568479 113.38580183 96.30568479 113.38580183 97.3203125 116.7265625 C97.81273437 117.84804687 98.30515625 118.96953125 98.8125 120.125 C107.79520771 142.3378486 104.36631182 165.91207917 95.67529297 187.55078125 C92.4814741 195.64553662 90.51469208 203.68543222 89.08544922 212.25537109 C88.68780468 214.49828146 88.19820031 216.70528162 87.69140625 218.92578125 C86.06482382 226.19234474 86.06482382 226.19234474 88.22265625 233.03515625 C90.43027244 235.24340532 90.43027244 235.24340532 92.98046875 237.2578125 C102.73909185 245.34071245 108.68972099 257.09645302 113.6875 268.5 C114.39519531 270.10875 114.39519531 270.10875 115.1171875 271.75 C122.68580519 290.93009948 125.26154319 312.74860529 125.8828125 333.25390625 C125.9147168 334.24181152 125.94662109 335.2297168 125.97949219 336.24755859 C126.03217176 338.11334495 126.06861076 339.97971703 126.08300781 341.84619141 C126.4385183 356.32926419 131.2331737 369.97445656 136.5 383.3125 C137.06361273 384.7637368 137.62675176 386.21515764 138.18945312 387.66674805 C143.3932189 401.01810712 148.90845808 414.24288423 154.48591614 427.44169617 C155.62803411 430.15102886 156.76053012 432.86426876 157.88818359 435.57965088 C158.41894568 436.85480111 158.95310193 438.12854413 159.49072266 439.40081787 C160.23605729 441.17192222 160.96224535 442.95104748 161.6875 444.73046875 C162.1 445.72844482 162.5125 446.7264209 162.9375 447.75463867 C163.76789169 450.79427231 163.61904915 452.51646244 162.6875 455.5 C161.6875 456.5 161.6875 456.5 159.3125 456.8125 C156.6875 456.5 156.6875 456.5 155.18164062 454.85571289 C153.46643634 452.15146351 152.32520333 449.47877663 151.15625 446.49609375 C150.68106934 445.2944458 150.20588867 444.09279785 149.71630859 442.85473633 C149.20664148 441.54901596 148.69704032 440.24326985 148.1875 438.9375 C147.38250836 436.89367203 146.57535371 434.85070792 145.76791382 432.80784607 C145.21715384 431.41435488 144.66704941 430.02060442 144.11758423 428.62660217 C141.93601054 423.09991919 139.68817833 417.60212371 137.421875 412.10961914 C133.17229169 401.80239526 129.08261868 391.44665367 125.1875 381 C124.77806152 379.90856689 124.36862305 378.81713379 123.94677734 377.69262695 C122.82151863 374.64047466 121.7424907 371.57707763 120.6875 368.5 C120.39222412 367.67653076 120.09694824 366.85306152 119.79272461 366.00463867 C117.05651699 357.44214527 116.89440652 348.57264787 116.40878296 339.66281128 C114.50982178 305.57457843 111.20407301 269.01657301 85.6875 243.5 C84.44523884 253.8138994 84.03564069 264.1223355 83.6875 274.5 C83.65205078 275.46309082 83.61660156 276.42618164 83.58007812 277.41845703 C83.4866669 280.2165045 83.42561375 283.01338335 83.375 285.8125 C83.33040649 287.07271973 83.33040649 287.07271973 83.28491211 288.35839844 C83.23285053 293.84075686 84.31042714 297.70817187 86.84179688 302.57885742 C87.6875 304.5 87.6875 304.5 87.5 307.5 C86.6875 309.5 86.6875 309.5 85.6875 310.5 C83.375 310.9375 83.375 310.9375 80.6875 310.5 C76.76944532 305.5598441 74.56075459 299.92478859 72.1875 294.125 C71.76460693 293.10583496 71.34171387 292.08666992 70.90600586 291.03662109 C68.30496736 284.69214198 65.84645325 278.30722127 63.47265625 271.875 C63.20387665 271.14840179 62.93509705 270.42180359 62.65817261 269.67318726 C61.32668605 266.06705904 60.00906196 262.45665087 58.7109375 258.83837891 C58.2254967 257.50935377 57.73983047 256.18041096 57.25390625 254.8515625 C56.83052979 253.67416504 56.40715332 252.49676758 55.97094727 251.28369141 C54.86097602 248.23767365 54.86097602 248.23767365 51.6875 246.5 C48.13332242 246.0462752 46.37392854 246.03619693 43.375 248.0625 C40.85752327 251.69885527 40.28265142 255.26433334 41.07739258 259.65307617 C41.72978667 262.06784221 42.4690496 264.43620935 43.25 266.8125 C43.52158936 267.6775415 43.79317871 268.54258301 44.07299805 269.43383789 C46.21619577 276.20861103 48.45819253 282.95584271 50.76977539 289.67504883 C54.56692468 300.78522638 53.95211148 310.23855888 52.125 321.6875 C49.60078567 338.07676984 50.15936639 354.42645012 60.02734375 368.5 C62.97784454 372.05448566 66.34321112 375.17951291 69.703125 378.33984375 C86.9970518 394.75180685 93.59648691 412.99075568 99.625 435.75 C99.93195801 436.90459717 100.23891602 438.05919434 100.55517578 439.2487793 C101.9589291 444.76548938 103.21103023 449.79754761 102.6875 455.5 C101.6875 456.5 101.6875 456.5 98.625 456.5625 C97.655625 456.541875 96.68625 456.52125 95.6875 456.5 C92.9512448 449.81137618 91.20803932 442.98704317 89.44284058 435.98739624 C85.50603463 420.50478172 81.56413708 405.71975691 70.6875 393.5 C69.4809375 391.953125 69.4809375 391.953125 68.25 390.375 C65.54145506 387.33614471 62.65120748 384.74989522 59.55859375 382.11328125 C57.49823837 380.33681618 55.57126398 378.46225415 53.6875 376.5 C53.130625 376.69335938 52.57375 376.88671875 52 377.0859375 C49.57003017 377.91508261 47.13011108 378.70894902 44.6875 379.5 C43.511875 379.891875 42.33625 380.28375 41.125 380.6875 C28.74959078 383.60226704 14.45203692 382.01054226 3.4375 375.75 C-10.97009348 366.32167083 -18.91319853 353.14448861 -22.625 336.3125 C-24.72974297 322.17189673 -23.07477806 309.05385217 -19.93310547 295.24804688 C-18.79727538 290.21858052 -17.74497264 285.17142009 -16.6875 280.125 C-16.36676514 278.60495361 -16.36676514 278.60495361 -16.03955078 277.05419922 C-14.47986331 269.56696424 -13.20883674 262.09879508 -12.3125 254.5 C-12.79976563 254.97308594 -13.28703125 255.44617188 -13.7890625 255.93359375 C-18.35452118 260.19192157 -23.02638405 263.72202542 -28.3125 267 C-51.69278408 281.70159221 -62.66632928 306.53933016 -74.11083984 330.72558594 C-74.90868896 332.41022949 -74.90868896 332.41022949 -75.72265625 334.12890625 C-76.19840088 335.14025635 -76.67414551 336.15160645 -77.16430664 337.19360352 C-78.3125 339.5 -78.3125 339.5 -79.3125 340.5 C-81.31208364 340.54080783 -83.31295254 340.54254356 -85.3125 340.5 C-86.82769086 337.59075497 -87.49651023 336.15834493 -86.59667969 332.93896484 C-86.14711914 332.03871582 -85.69755859 331.1384668 -85.234375 330.2109375 C-84.7379248 329.19620361 -84.24147461 328.18146973 -83.72998047 327.13598633 C-83.17971191 326.05986084 -82.62944336 324.98373535 -82.0625 323.875 C-81.50836426 322.76213623 -80.95422852 321.64927246 -80.38330078 320.50268555 C-78.71052845 317.15929838 -77.01248911 313.82960941 -75.3125 310.5 C-74.41829079 308.70751983 -73.52497568 306.91459316 -72.6328125 305.12109375 C-62.87602101 285.76916175 -50.75827096 268.72970605 -32.02392578 257.19604492 C-19.00158136 249.15792406 -11.39066257 239.15158681 -7.5 224.1875 C-5.53151456 215.63353599 -5.06077313 207.24109131 -4.8828125 198.50195312 C-4.55623887 189.17419373 -2.12053197 181.38390368 2.375 173.25 C2.71877686 172.62230713 3.06255371 171.99461426 3.41674805 171.34790039 C6.50989817 165.72967244 9.70530974 160.16709845 12.92578125 154.62109375 C16.64327167 148.03511848 19.07479361 143.15629018 17.6875 135.5 C15.75524841 132.63645906 15.75524841 132.63645906 12.6875 131.5 C9.71240015 131.33220521 9.71240015 131.33220521 6.6875 132.5 C4.81583764 134.82502739 3.44186163 136.86639678 2 139.4375 C1.57775146 140.14970703 1.15550293 140.86191406 0.72045898 141.59570312 C-0.17911874 143.1137715 -1.07076569 144.63656302 -1.95507812 146.16357422 C-4.16863174 149.97359366 -6.45711556 153.73734926 -8.75 157.5 C-9.20286377 158.24531982 -9.65572754 158.99063965 -10.12231445 159.75854492 C-13.34162797 165.0178758 -16.69978761 170.16486663 -20.1875 175.25 C-20.62763428 175.89324219 -21.06776855 176.53648437 -21.52124023 177.19921875 C-24.26291729 181.14614893 -27.04506291 184.97009666 -30.3125 188.5 C-33.5625 188.9375 -33.5625 188.9375 -36.3125 188.5 C-36.6425 188.17 -36.9725 187.84 -37.3125 187.5 C-36.9729981 180.22751193 -33.68427679 176.7404125 -29.1484375 171.3671875 C-27.10086241 168.7241239 -27.10086241 168.7241239 -27.27734375 166.0546875 C-28.63908132 162.69402195 -30.52363608 159.77010229 -32.5 156.75 C-37.52961302 148.78049316 -40.51647915 140.45823151 -43.3125 131.5 C-57.84306215 148.52397222 -62.55089246 170.31877502 -67.4375 191.625 C-67.85726169 193.43117831 -68.27783281 195.23716869 -68.69921875 197.04296875 C-68.90588669 197.9289122 -69.11255463 198.81485565 -69.32548523 199.72764587 C-69.63229973 201.04195335 -69.63229973 201.04195335 -69.9453125 202.3828125 C-70.14683426 203.24616714 -70.34835602 204.10952179 -70.5559845 204.9990387 C-71.1403143 207.49963593 -71.72629807 209.99984108 -72.3125 212.5 C-72.49187103 213.26964081 -72.67124207 214.03928162 -72.85604858 214.83224487 C-76.40329377 229.96318905 -76.40329377 229.96318905 -79.875 236.8125 C-80.21595703 237.50867432 -80.55691406 238.20484863 -80.90820312 238.92211914 C-89.29379991 255.72133943 -99.56632915 271.57115926 -109.45458984 287.50537109 C-111.1363434 290.21606611 -112.81306849 292.92979156 -114.48828125 295.64453125 C-115.38765903 297.09657832 -116.28736793 298.54842039 -117.1875 300 C-117.58590088 300.64606201 -117.98430176 301.29212402 -118.39477539 301.95776367 C-119.89865296 304.37099368 -121.29405354 306.48155354 -123.3125 308.5 C-126.4375 308.625 -126.4375 308.625 -129.3125 308.5 C-130.16856674 305.11596754 -130.58142764 303.14999918 -129.22705078 299.87646484 C-128.37602783 298.55702881 -128.37602783 298.55702881 -127.5078125 297.2109375 C-126.8698877 296.2010376 -126.23196289 295.1911377 -125.57470703 294.15063477 C-124.86942871 293.06967529 -124.16415039 291.98871582 -123.4375 290.875 C-122.7087824 289.72904771 -121.98209291 288.5818035 -121.25732422 287.43334961 C-119.73127281 285.01738256 -118.19821239 282.60609484 -116.66015625 280.19775391 C-112.84103158 274.20099221 -109.13118588 268.13709769 -105.4375 262.0625 C-105.07977509 261.47426453 -104.72205017 260.88602905 -104.35348511 260.27996826 C-99.9024144 252.9444945 -95.54440175 245.56907534 -91.5 238 C-91.12182129 237.30205322 -90.74364258 236.60410645 -90.35400391 235.88500977 C-84.61521191 224.84450359 -82.14876094 212.87675503 -79.56460571 200.8119812 C-76.19416027 185.14499361 -72.59974519 169.65092729 -67.3125 154.5 C-67.05903809 153.76587891 -66.80557617 153.03175781 -66.54443359 152.27539062 C-63.57091423 143.8281998 -59.87683143 136.55453321 -54.3125 129.5 C-53.631875 128.55125 -52.95125 127.6025 -52.25 126.625 C-50.3125 124.5 -50.3125 124.5 -47.2890625 123.1328125 C-42.61074638 118.99477435 -43.13665412 114.24630811 -42.75 108.25 C-40.3761132 81.9247396 -40.3761132 81.9247396 -31.546875 71.98046875 C-30.07657923 70.39997265 -30.07657923 70.39997265 -29.3125 67.5 C-30.46199981 64.82083424 -30.46199981 64.82083424 -32.125 61.9375 C-38.63892388 49.30260357 -39.2336063 34.94472368 -35.28515625 21.28125 C-32.01640444 11.93445767 -27.68139874 5.37060142 -19.625 -0.4375 C-13.2821116 -2.47201137 -6.18933202 -2.71461931 0 0 Z M-20.3125 11.5 C-27.91725776 20.11872546 -28.96648066 31.66882521 -28.59765625 42.69140625 C-27.96113258 51.19292107 -25.19857739 57.58610392 -20.3125 64.5 C-19.45096313 64.2525 -19.45096313 64.2525 -18.57202148 64 C-16.32109982 63.50190302 -14.45712121 63.43244997 -12.16015625 63.5 C-3.71569518 63.84414394 -3.71569518 63.84414394 3.91015625 60.9609375 C9.47110548 51.87975435 9.75605292 37.70587507 7.6875 27.5 C5.73867512 19.80002345 2.70194632 13.79650565 -3.3125 8.5 C-10.00439813 4.76498709 -14.81938295 7.01358966 -20.3125 11.5 Z M21.078125 31.74609375 C14.8306317 39.62565692 14.90251325 48.86509411 15.6875 58.5 C15.75066406 59.345625 15.81382812 60.19125 15.87890625 61.0625 C16.41093911 63.59325089 16.83787329 64.66394023 18.6875 66.5 C23.24131022 68.67767603 27.82812809 70.16479609 32.6875 71.5 C39.13700019 65.39912144 40.5962152 56.96694448 41.125 48.3125 C40.38500992 41.86401506 38.29158708 36.56842807 34.3125 31.4375 C29.40029862 27.81182755 25.7040913 27.27838419 21.078125 31.74609375 Z M52.1484375 49.00390625 C47.09195017 54.18207376 46.32471688 61.00736153 46.40625 67.88671875 C46.84711043 71.9830469 48.13745862 75.25828073 50.6875 78.5 C52.94463191 80.1681042 52.94463191 80.1681042 55.6875 79.5 C60.09841375 77.04624666 62.87170812 73.91557147 64.625 69.1875 C66.6535194 61.69079785 66.50763379 55.32166747 62.6875 48.5 C58.32875706 44.4054233 56.57619148 45.19171807 52.1484375 49.00390625 Z M74.0625 71.6875 C70.03487953 76.45705056 69.30586245 80.29136067 69.41796875 86.40625 C69.76647957 89.11352249 70.72900335 90.62310738 72.6875 92.5 C75.73011908 92.1740051 76.6676219 91.52104739 78.8125 89.25 C82.50081505 83.84047127 83.09620462 79.93709776 82.6875 73.5 C81.82484032 71.09442147 81.82484032 71.09442147 80.6875 69.5 C76.63015015 69.0732104 76.63015015 69.0732104 74.0625 71.6875 Z M-23.1875 75.8125 C-27.47397702 81.23363271 -30.00259983 85.75922161 -31.5 92.4375 C-31.66435547 93.11490234 -31.82871094 93.79230469 -31.99804688 94.49023438 C-37.017932 115.68756305 -35.3070576 135.02211615 -24.21484375 153.796875 C-22.53180559 156.75680008 -22.53180559 156.75680008 -19.3125 157.5 C-18.57930542 156.26697144 -18.57930542 156.26697144 -17.83129883 155.0090332 C-16.00297401 151.93878665 -14.16491621 148.87446274 -12.32397461 145.81176758 C-11.53097295 144.48945225 -10.74056283 143.16557896 -9.95288086 141.84008789 C-8.81534012 139.92691849 -7.66836656 138.01968448 -6.51953125 136.11328125 C-6.17348343 135.52662186 -5.82743561 134.93996246 -5.47090149 134.33552551 C-2.81789803 129.96396585 0.12450184 125.73472904 4.828125 123.46875 C10.71917917 122.15962685 15.3532369 122.51239916 20.6875 125.5 C23.98734034 128.46199954 26.49915214 131.67302575 26.9609375 136.15234375 C27.22340379 144.64211866 25.79616937 150.14282812 21.6875 157.5 C20.9047199 158.92174948 20.12218735 160.34363528 19.33984375 161.765625 C17.61667116 164.88214804 15.8780333 167.98953235 14.1328125 171.09375 C7.1859418 183.06282771 7.1859418 183.06282771 4.29296875 196.35546875 C3.63189565 208.03228493 2.9438403 218.98084602 -0.3125 230.234375 C-1.77556568 235.82812613 -2.1829385 241.5730767 -2.75 247.3125 C-4.34486233 263.14823231 -6.84546285 278.86886155 -10.74609375 294.3125 C-15.85414853 314.54395038 -17.25178327 333.94027035 -7.125 352.875 C-0.85242977 362.87648672 7.39988467 368.46930447 18.54296875 372.10546875 C29.39084389 374.10116163 38.94998548 372.66383346 48.6875 367.5 C48.33816406 366.47519531 47.98882812 365.45039063 47.62890625 364.39453125 C47.16910964 363.03390863 46.7094832 361.67322849 46.25 360.3125 C46.01990234 359.63896484 45.78980469 358.96542969 45.55273438 358.27148438 C43.02962618 350.77529337 42.49497905 344.28901048 42.5 336.4375 C42.49935547 335.40125488 42.49871094 334.36500977 42.49804688 333.29736328 C42.54050417 327.15938972 42.97426942 321.39054976 44.19677734 315.36474609 C46.28041912 303.20083934 43.19640254 293.26380898 39.25 281.9375 C38.72668618 280.39319686 38.20518993 278.84827656 37.68554688 277.30273438 C36.95612418 275.13401028 36.22433438 272.96651202 35.47792053 270.80357361 C32.65301832 262.61135073 31.00548638 254.45751383 33.875 246 C36.99215742 241.70047253 40.56725521 238.96292708 45.6875 237.5 C51.13942962 236.9951917 54.91316927 237.79754864 59.6875 240.5 C62.67455024 244.45873269 64.58341916 248.34398716 66.265625 252.9921875 C66.70390625 254.19101562 67.1421875 255.38984375 67.59375 256.625 C68.0371875 257.8625 68.480625 259.1 68.9375 260.375 C69.40031122 261.64870315 69.8638466 262.92214342 70.328125 264.1953125 C71.45505437 267.29436828 72.57457507 270.39589337 73.6875 273.5 C74.0175 273.5 74.3475 273.5 74.6875 273.5 C74.75743164 272.33879639 74.82736328 271.17759277 74.89941406 269.98120117 C78.88725641 204.69168772 78.88725641 204.69168772 88.75 180.9375 C96.53805788 162.05485841 97.19382108 141.83696825 90.6875 122.5 C90.28917969 121.28957031 90.28917969 121.28957031 89.8828125 120.0546875 C84.94021279 108.05123106 70.25627872 100.92676746 59.6875 94.5 C59.02975586 94.09749023 58.37201172 93.69498047 57.69433594 93.28027344 C38.27543768 81.52231318 -1.81528205 58.62180295 -23.1875 75.8125 Z M90.6875 89.5 C87.78536078 92.74356737 85.83911008 95.07486524 85.375 99.4375 C85.36956991 102.57686551 85.36956991 102.57686551 87.5625 104.375 C89.5813588 105.65596257 89.5813588 105.65596257 91.6875 105.5 C94.69724609 100.48375652 95.06687519 97.19062784 94.6875 91.5 C94.3575 90.84 94.0275 90.18 93.6875 89.5 C92.6975 89.5 91.7075 89.5 90.6875 89.5 Z \" fill=\"#FFFFFF\" transform=\"translate(239.3125,28.5)\"><\/path><path d=\"M0 0 C5.80782957 4.77532654 10.68502759 9.99931358 12.8125 17.3125 C12.5 21.25 12.5 21.25 11.8125 24.3125 C9.5 25 9.5 25 6.8125 25.3125 C4.27110595 23.32331009 3.34973764 21.48224121 2.4375 18.4375 C0.35323117 12.52121609 -3.6738628 9.14000626 -9.1875 6.3125 C-15.58546952 4.35337871 -22.69610306 4.21035507 -28.75 7.1875 C-30.95741085 8.42658717 -32.37664731 9.50164731 -34.1875 11.3125 C-36.6875 11.5625 -36.6875 11.5625 -39.1875 11.3125 C-41.1875 9.3125 -41.1875 9.3125 -41.25 7.0625 C-39.34929283 2.14302263 -35.59720929 -0.60756339 -30.8515625 -2.734375 C-20.10759741 -6.32699424 -9.98312913 -5.28518601 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(272.1875,135.6875)\"><\/path><path d=\"M0 0 C3.46023238 2.70800795 6.58353052 5.46188809 8.875 9.25 C8.75 12.1875 8.75 12.1875 7.875 14.25 C5.1875 15.125 5.1875 15.125 1.875 15.25 C-0.5 12.5625 -0.5 12.5625 -1.72265625 10.8828125 C-5.47462621 6.51422352 -11.45192494 4.65818236 -17.0546875 4.21875 C-24.04244132 4.32422553 -30.13516749 6.23521833 -35.125 11.25 C-36.55280423 13.30634849 -37.80567913 15.37014542 -38.984375 17.578125 C-40.125 19.25 -40.125 19.25 -43.125 20.25 C-44.115 19.92 -45.105 19.59 -46.125 19.25 C-47.06377933 16.3614482 -47.50075505 14.19897321 -46.359375 11.31640625 C-42.10119935 4.03492588 -36.00578214 -2.01170984 -27.74609375 -4.31640625 C-17.39310342 -6.02904698 -9.09742098 -5.09455575 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(303.125,249.75)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMassage des pieds\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUn soin rafra\u00eechissant qui stimule les points de pression de vos pieds et d\u00e9tend tout votre corps.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aebf3a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"aebf3a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-3018dd8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3018dd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/voetreflexmassage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apprendre plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fcb57ec e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"fcb57ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd9ca46 elementor-widget elementor-widget-image\" data-id=\"fd9ca46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Body-Massage-200x200-1.png\" class=\"attachment-full size-full wp-image-987811\" alt=\"\" srcset=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Body-Massage-200x200-1.png 200w, https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/09\/Body-Massage-200x200-1-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-778c3ae elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"778c3ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\" viewbox=\"0 0 512 512\"><path d=\"M0 0 C4.58802594 4.91341785 7.24500924 11.14155014 7.5625 17.875 C6.68245497 25.66968456 3.98482138 31.45570553 -1.875 36.75 C-9.77189402 42.84303498 -18.60981135 46.33650944 -27.875 49.75 C-27.41609375 50.1625 -26.9571875 50.575 -26.484375 51 C-25.87078125 51.5775 -25.2571875 52.155 -24.625 52.75 C-23.72007812 53.5853125 -23.72007812 53.5853125 -22.796875 54.4375 C-21.00057935 56.5988964 -20.20282332 58.207218 -19.1171875 60.75 C-16.8619321 65.46117182 -13.93989226 66.8243126 -9.25 68.75 C-0.82444057 72.57119345 6.70894327 77.02742069 12.125 84.75 C12.51429688 84.14414063 12.90359375 83.53828125 13.3046875 82.9140625 C26.48827641 63.16905607 44.76251731 54.07836559 67.4375 49.25 C71.2837084 48.50677132 73.66731241 48.82777969 77.125 50.75 C85.9891425 64.32149767 86.6890951 86.16081282 83.890625 101.65234375 C82.11054472 108.85440324 79.03471957 115.46937177 75.125 121.75 C76.1975 121.811875 77.27 121.87375 78.375 121.9375 C87.89850094 123.15111428 96.57939438 128.02329743 104.125 133.75 C105.10533203 134.48283203 105.10533203 134.48283203 106.10546875 135.23046875 C115.15603933 142.54679826 123.89698336 153.86547781 128.125 164.75 C128.4375 168.5625 128.4375 168.5625 127.125 171.75 C117.1227755 182.97200797 98.75216284 190.56914289 84.125 192.75 C81.34193318 192.86907649 78.59491898 192.93505284 75.8125 192.9375 C75.09126953 192.94974609 74.37003906 192.96199219 73.62695312 192.97460938 C68.48104523 192.98845487 64.0736185 192.16468981 59.125 190.75 C59.455 191.41 59.785 192.07 60.125 192.75 C61.14798939 209.47000686 58.13478434 221.93189898 50.125 236.75 C50.86234375 237.02585937 51.5996875 237.30171875 52.359375 237.5859375 C64.40741334 242.65700449 74.15017363 252.2637687 80.125 263.75 C83.33324365 271.75451426 83.51416412 281.0118749 80.5 289.125 C78.30626641 293.82805691 75.50869753 297.83116783 72.125 301.75 C71.64675781 302.32234375 71.16851562 302.8946875 70.67578125 303.484375 C35.64245116 341.95926648 -38.68439679 346.15443304 -86.61054993 348.50169373 C-147.5981188 351.21795554 -232.48529497 349.53413719 -283.875 311.75 C-284.81730469 311.06292969 -285.75960937 310.37585938 -286.73046875 309.66796875 C-296.67179823 302.00737612 -303.72815652 292.94561942 -305.6875 280.375 C-306.44476569 270.76101822 -303.27242105 262.61121198 -297.875 254.75 C-293.46957418 249.59588822 -288.71993376 245.19701222 -282.875 241.75 C-286.16204345 239.10747488 -289.65643379 237.22653519 -293.375 235.25 C-305.51175069 228.52437685 -316.71518265 218.76052983 -321.25 205.375 C-324.16785365 194.79015016 -323.45935525 185.86765131 -318.50390625 176.02734375 C-304.84703208 152.74188203 -276.50906926 143.4431416 -251.875 136.75 C-250.54265338 136.41274437 -249.20960326 136.07821187 -247.875 135.75 C-247.81183594 134.79480469 -247.74867188 133.83960938 -247.68359375 132.85546875 C-246.79515032 123.47537649 -244.75755341 117.36194551 -238.875 109.75 C-238.30652344 108.99074219 -237.73804688 108.23148438 -237.15234375 107.44921875 C-236.73082031 106.88847656 -236.30929688 106.32773438 -235.875 105.75 C-236.69742188 105.34910156 -237.51984375 104.94820313 -238.3671875 104.53515625 C-249.34968178 98.9424542 -259.87093537 92.18999109 -264.1875 80.0625 C-265.85571708 72.11572047 -264.68831894 64.65992552 -260.36328125 57.80078125 C-247.22034501 39.69043604 -220.79901117 33.17903395 -199.875 29.75 C-198.555 29.75 -197.235 29.75 -195.875 29.75 C-196.37 28.615625 -196.865 27.48125 -197.375 26.3125 C-199.88110755 19.54600963 -199.70369215 13.20890646 -196.828125 6.58203125 C-190.69769961 -5.20145035 -177.06125084 -10.78437603 -164.99462891 -14.61376953 C-158.36270497 -16.60441613 -151.69104521 -18.04716849 -144.875 -19.25 C-144.06240723 -19.40098145 -143.24981445 -19.55196289 -142.41259766 -19.70751953 C-101.51153421 -26.96959304 -33.13683235 -29.97089295 0 0 Z M-179.875 9.75 C-180.7 10.41 -181.525 11.07 -182.375 11.75 C-184.44772499 14.51363331 -184.875 16.29347541 -184.875 19.75 C-181.62948564 27.37695875 -173.69063283 31.1823369 -166.34765625 34.19921875 C-145.14458484 41.60805692 -123.18652166 43.11236265 -100.90039062 43.06567383 C-97.77438053 43.06252456 -94.64933094 43.08604011 -91.5234375 43.11132812 C-67.68897703 43.18623883 -42.74937862 41.3530087 -21 30.8125 C-20.35160156 30.50094971 -19.70320312 30.18939941 -19.03515625 29.8684082 C-14.45382019 27.48229567 -11.77609657 24.92582081 -8.875 20.75 C-8.72446192 16.45966478 -9.28532625 14.50049386 -11.9375 11.125 C-47.22642767 -17.40647344 -144.21933011 -19.01491122 -179.875 9.75 Z M-197.8125 45.4375 C-199.32831665 45.70759888 -199.32831665 45.70759888 -200.87475586 45.9831543 C-216.17654858 48.81690928 -237.55382934 52.87220908 -247.875 65.75 C-250.42325184 69.85411518 -251.14690761 72.55778969 -250.0625 77.3125 C-243.98089635 88.44107762 -230.14459202 93.26337231 -218.671875 96.81274414 C-169.45770778 110.96956225 -108.86687231 110.51037179 -59.875 95.75 C-59.85518066 95.02409668 -59.83536133 94.29819336 -59.81494141 93.55029297 C-59.7193181 90.24151525 -59.60978993 86.9333367 -59.5 83.625 C-59.4690625 82.48289063 -59.438125 81.34078125 -59.40625 80.1640625 C-59.36757813 79.05546875 -59.32890625 77.946875 -59.2890625 76.8046875 C-59.2576416 75.78874512 -59.2262207 74.77280273 -59.19384766 73.72607422 C-58.84329721 70.45409114 -58.15687396 67.78091259 -56.875 64.75 C-53.23780395 62.32520264 -51.01796518 62.36337423 -46.6875 62.125 C-45.41519531 62.05023438 -44.14289063 61.97546875 -42.83203125 61.8984375 C-41.36830078 61.82496094 -41.36830078 61.82496094 -39.875 61.75 C-42.87676552 58.40187692 -45.67371391 56.38902025 -49.875 54.75 C-53.13571406 54.56474503 -53.13571406 54.56474503 -56.5 55 C-58.15902344 55.16242188 -58.15902344 55.16242188 -59.8515625 55.328125 C-62.00321813 55.5531275 -64.154556 55.7802162 -66.30541992 56.01269531 C-76.17011731 56.96681183 -86.03553007 56.99351649 -95.9375 57 C-97.32986877 57.00101212 -97.32986877 57.00101212 -98.75036621 57.00204468 C-124.20500452 56.97276194 -153.06869013 56.47265001 -176.2421875 44.66796875 C-183.14586341 42.26090074 -190.81450187 44.19051162 -197.8125 45.4375 Z M66.125 64.75 C50.32517019 69.56884148 36.1762416 75.05417062 27.75 90.3125 C25.15562838 95.8585947 23.97940208 101.38027145 23.14892578 107.40649414 C22.74105434 110.22289871 22.40778444 112.35552759 20.73046875 114.6953125 C18.18686729 116.36629156 16.08119303 116.05793677 13.125 115.75 C9.30406805 113.20271203 9.1607738 111.45244924 7.8125 107.125 C5.79437129 101.10276917 3.5178837 96.37356024 -0.875 91.75 C-1.52210938 91.06292969 -2.16921875 90.37585938 -2.8359375 89.66796875 C-8.49315777 84.16392231 -14.44726284 81.27030806 -21.875 78.75 C-22.55175781 78.51539063 -23.22851562 78.28078125 -23.92578125 78.0390625 C-30.36634077 76.13585647 -37.21031335 76.10569957 -43.875 75.75 C-44.61541092 91.21636144 -43.34894337 106.43007427 -32.875 118.75 C-27.26627158 124.32044359 -18.21585541 131.75 -9.875 131.75 C-8.66964286 139.78571429 -8.66964286 139.78571429 -9.875 143.75 C-10.99777344 143.79898438 -12.12054688 143.84796875 -13.27734375 143.8984375 C-29.36568772 144.66771593 -41.82529819 146.54972175 -53.4765625 158.7890625 C-58.84718535 165.41924511 -65.875 175.04096706 -65.875 183.75 C-63.33486091 184.5675507 -60.79306769 185.37915186 -58.25 186.1875 C-57.53714844 186.41759766 -56.82429688 186.64769531 -56.08984375 186.88476562 C-43.49172568 190.87224336 -31.45538632 191.23664151 -19.34765625 185.56640625 C-14.32563931 182.83486237 -10.87374431 179.8110102 -7.1875 175.4375 C-2.67274536 170.12367374 -2.67274536 170.12367374 1 169.5 C4.125 169.75 4.125 169.75 7.125 171.75 C8.79863406 176.77090218 7.86719051 179.96990465 6.1875 184.9375 C2.94101215 194.76714376 2.93020627 204.1960214 7.125 213.75 C12.1181049 223.27614052 19.26857892 231.57734288 28.125 237.75 C28.785 237.75 29.445 237.75 30.125 237.75 C31.83579693 235.70309961 33.39762392 233.67099132 34.9375 231.5 C35.38601318 230.8704541 35.83452637 230.2409082 36.29663086 229.59228516 C43.84391227 218.67648958 47.18173167 207.97382275 46.125 194.75 C44.7928128 188.74791747 42.8015203 183.50535072 39.3125 178.4375 C37.2043039 175.35579438 37.12189758 174.8477263 37.25 170.8125 C38.125 167.75 38.125 167.75 39.125 166.75 C44.75891486 165.93052148 47.40659614 166.6039289 52 170 C53.2684375 170.95519531 53.2684375 170.95519531 54.5625 171.9296875 C62.92443759 177.86972243 72.35765099 179.43631134 82.4375 178.4140625 C91.95688851 176.74816951 105.65520672 172.50405937 112.125 164.75 C103.10638013 151.49917863 93.7774445 140.97267773 77.9375 136.375 C71.84034091 135.37546572 66.50915697 135.31276133 60.5 136.8125 C56.43682233 137.8087257 53.23151403 137.83948331 49.125 136.75 C46.77950326 133.23175489 46.54508597 131.89224306 47.125 127.75 C49.21516924 125.12043224 51.47930328 123.2074188 54.21484375 121.26953125 C63.69656071 114.44593665 68.52411997 106.26599245 70.69140625 94.796875 C72.03779037 85.33579743 71.53587946 72.86631919 66.125 64.75 Z M-61.8046875 110.73828125 C-70.77757304 113.14357446 -79.6678974 115.21194668 -88.875 116.5 C-90.10839111 116.67269409 -90.10839111 116.67269409 -91.36669922 116.84887695 C-102.08758447 118.26470159 -112.75549391 118.9113632 -123.56640625 118.953125 C-125.34264626 118.96167511 -125.34264626 118.96167511 -127.1547699 118.97039795 C-129.65321986 118.97978965 -132.15168188 118.98635853 -134.65014648 118.99023438 C-138.37572423 118.99984071 -142.1007254 119.03088027 -145.82617188 119.0625 C-165.5006651 119.1499994 -185.02692269 118.12569734 -204.26199341 113.74197388 C-212.18871 111.75037402 -212.18871 111.75037402 -220.05859375 112.84375 C-222.44750166 114.63248893 -224.08650069 116.37282378 -225.875 118.75 C-226.38804687 119.25660156 -226.90109375 119.76320313 -227.4296875 120.28515625 C-230.91816267 123.82290367 -232.64560652 127.83715623 -232.875 132.75 C-230.43834811 141.43057236 -225.07778398 146.27919796 -217.5625 150.8125 C-186.7822022 167.90812115 -147.86837546 169.96450355 -113.42260742 169.88037109 C-110.8122784 169.87499954 -108.20212081 169.88035867 -105.59179688 169.88671875 C-100.68501186 169.89077991 -95.78096834 169.83531092 -90.875 169.75 C-90.15732452 169.74206421 -89.43964905 169.73412842 -88.70022583 169.72595215 C-86.74746105 169.69608569 -84.79541827 169.62661291 -82.84375 169.5546875 C-81.76416016 169.52101074 -80.68457031 169.48733398 -79.57226562 169.45263672 C-76.67590688 168.97334209 -76.67590688 168.97334209 -74.86376953 166.38842773 C-73.37355056 163.7283702 -73.37355056 163.7283702 -72.1484375 160.73046875 C-66.30965358 147.06484872 -53.75941967 139.6148852 -40.875 133.75 C-41.43767578 133.02296875 -41.43767578 133.02296875 -42.01171875 132.28125 C-47.50099283 125.09126884 -51.95640019 118.35218893 -54.875 109.75 C-57.54617645 109.75 -59.27488997 110.03878306 -61.8046875 110.73828125 Z M-255.1875 153.3125 C-256.5022229 153.71577515 -256.5022229 153.71577515 -257.84350586 154.12719727 C-270.65729192 158.15313077 -282.94621063 162.78147896 -293.875 170.75 C-294.53886719 171.21921875 -295.20273437 171.6884375 -295.88671875 172.171875 C-301.63603977 176.61169774 -305.58675166 182.88525499 -307.875 189.75 C-308.73495235 197.91954737 -306.07988429 203.73223445 -300.99609375 210.10546875 C-274.57669527 238.37373858 -224.84286981 242.68585822 -188.875 245.75 C-188.05644531 245.82202637 -187.23789063 245.89405273 -186.39453125 245.96826172 C-130.00239608 250.67176503 -63.20320211 248.74991315 -12.875 220.75 C-12.05128906 220.37617188 -11.22757812 220.00234375 -10.37890625 219.6171875 C-8.46342258 217.23900258 -8.72305003 216.30120346 -8.921875 213.30078125 C-9.13466352 211.5519256 -9.36996045 209.8056953 -9.625 208.0625 C-9.7384375 207.16982422 -9.851875 206.27714844 -9.96875 205.35742188 C-10.25183571 203.15171237 -10.55453044 200.95053652 -10.875 198.75 C-11.43767578 198.94698486 -12.00035156 199.14396973 -12.58007812 199.34692383 C-22.56120636 202.76929431 -33.24421321 205.75635675 -43.875 204.75 C-44.79925781 204.66878906 -45.72351563 204.58757812 -46.67578125 204.50390625 C-53.45395906 203.68512263 -59.7852484 201.99969055 -66.25 199.875 C-67.37329712 199.50834229 -67.37329712 199.50834229 -68.51928711 199.13427734 C-70.66615464 198.39816748 -72.76953828 197.59679446 -74.875 196.75 C-75.5546582 196.49573242 -76.23431641 196.24146484 -76.93457031 195.97949219 C-78.8515625 195.1171875 -78.8515625 195.1171875 -81.875 192.75 C-82.38900757 190.55007935 -82.38900757 190.55007935 -82.56396484 188.10205078 C-82.62949554 187.28809845 -82.69502625 186.47414612 -82.76254272 185.63552856 C-82.81820908 184.70219193 -82.81820908 184.70219193 -82.875 183.75 C-84.64653442 183.76571045 -84.64653442 183.76571045 -86.45385742 183.78173828 C-204.72814644 184.73506974 -204.72814644 184.73506974 -234.95703125 155.75390625 C-236.06990142 154.54890304 -237.15159185 153.31325331 -238.1796875 152.03515625 C-242.91950144 148.44207149 -250.07748423 151.73046548 -255.1875 153.3125 Z M-7.0625 233.3125 C-28.38864149 246.36556936 -53.48476305 251.79268122 -77.875 255.75 C-78.8232666 255.90452637 -79.7715332 256.05905273 -80.74853516 256.21826172 C-94.16472354 258.31993422 -107.6406293 259.20958219 -121.1875 259.9375 C-121.9750769 259.98047211 -122.76265381 260.02344421 -123.57409668 260.06771851 C-166.97236955 262.3762457 -212.5224306 261.08703814 -254.54736328 249.23681641 C-260.20346959 247.6572016 -260.20346959 247.6572016 -265.875 248.75 C-275.01326163 253.99192216 -283.99029922 260.70739938 -288.9375 270.25 C-290.39239006 275.68158956 -290.22529192 279.9749173 -287.7421875 285.078125 C-273.67138539 307.68367592 -240.02198017 316.74251731 -215.875 322.75 C-198.07386344 326.81581641 -180.04282967 329.90893589 -161.875 331.75 C-160.40184326 331.9044458 -160.40184326 331.9044458 -158.89892578 332.06201172 C-126.62161522 335.29843459 -93.12488322 335.24006235 -60.875 331.75 C-59.67987793 331.62109375 -58.48475586 331.4921875 -57.25341797 331.359375 C-17.47837043 326.89340475 35.89954271 319.99196877 63.859375 287.75 C66.95975405 283.43037076 67.91455282 279.56770496 67.59765625 274.26171875 C65.96635611 265.5929089 60.00242451 259.80572576 53.125 254.75 C49.20090941 252.26914465 45.20702746 249.96023484 41.125 247.75 C39.9803125 248.925625 39.9803125 248.925625 38.8125 250.125 C34.20932396 254.62112543 34.20932396 254.62112543 30.265625 255.08984375 C20.1468649 253.99490329 8.91261989 241.29257258 2.6875 233.6875 C1.841875 232.718125 0.99625 231.74875 0.125 230.75 C-3.35958682 230.75 -4.20816014 231.43089559 -7.0625 233.3125 Z \" fill=\"#FFFFFF\" transform=\"translate(349.875,136.25)\"><\/path><path d=\"M0 0 C2.79782492 2.19490381 3.47478938 4.08907326 4.25 7.5 C6.70137604 16.24579474 11.74289125 23.04751663 18.29296875 29.18359375 C24.5105874 35.79959529 27.380104 43.10843641 27.2890625 52.13671875 C26.91105255 55.88106054 26.09116659 59.47972218 25.1875 63.125 C25.0222583 63.79378174 24.8570166 64.46256348 24.68676758 65.15161133 C23.50969427 69.64664657 21.91811689 73.76805157 20 78 C20.61488281 77.65066406 21.22976563 77.30132812 21.86328125 76.94140625 C22.67152344 76.48636719 23.47976563 76.03132813 24.3125 75.5625 C25.11300781 75.11003906 25.91351563 74.65757813 26.73828125 74.19140625 C35.03438038 69.82126767 47.25492585 71.19663672 56.0625 73.5 C71.4018354 78.49583859 87.90763062 87.33425847 100 98 C101.54163175 101.0832635 101.29747535 103.60878099 101 107 C98.0293659 109.87824595 94.67852942 110.93822897 90.8125 112.25 C84.50428554 114.61294321 80.03147763 117.59745707 75 122 C73.13222689 123.59185208 71.2569283 125.17490784 69.375 126.75 C68.51648438 127.48734375 67.65796875 128.2246875 66.7734375 128.984375 C61.1717699 133.0554461 55.92527299 134.56408566 49.0625 134.5 C47.95660522 134.49033203 47.95660522 134.49033203 46.82836914 134.48046875 C27.45389365 133.85235309 5.38261698 122.19104826 -8.8359375 109.4609375 C-11.21940905 106.75049152 -11.65006139 104.70527072 -12.3671875 101.23046875 C-14.61147032 93.32006449 -20.42350932 87.1945775 -25.8828125 81.3125 C-32.86326502 73.6880943 -35.53698862 66.7354916 -35.3046875 56.359375 C-33.49122963 36.36483949 -21.22842293 14.73002769 -8 0 C-5.06317146 -1.46841427 -3.13175678 -0.76696084 0 0 Z M-7 23 C-18.34481202 41.25487877 -18.34481202 41.25487877 -21 62 C-18.5191363 67.82463651 -14.47022599 71.94793948 -10.1875 76.5546875 C-8.29350151 78.67190724 -6.6570586 80.7806192 -5.0625 83.125 C-4.381875 84.07375 -3.70125 85.0225 -3 86 C-2.34 86 -1.68 86 -1 86 C9.8302976 68.68240961 9.8302976 68.68240961 13 49 C11.15948247 43.6271761 8.61871703 40.04607164 4.625 36 C0.68521043 31.87531056 -2.78715972 27.71216574 -6 23 C-6.33 23 -6.66 23 -7 23 Z M27 93 C25.64944602 94.21236989 24.29525877 95.42070439 22.9375 96.625 C21.96103516 97.49705078 21.96103516 97.49705078 20.96484375 98.38671875 C18.15945804 100.69014678 15.21459509 102.32573173 12 104 C15.38461925 107.88926686 19.12825547 109.85643101 23.6875 112.0625 C24.40357422 112.41320557 25.11964844 112.76391113 25.85742188 113.12524414 C34.15554607 117.12666282 42.91303275 121.14400448 52.3046875 119.37890625 C56.80097805 117.70111495 59.52945995 115.35539107 63 112.125 C67.4383859 108.05317722 71.65881401 104.82047322 77 102 C66.68412837 93.08086147 51.350143 86.09790345 37.59765625 86.5234375 C33.05308776 87.35717788 30.29231068 89.90414407 27 93 Z \" fill=\"#FFFFFF\" transform=\"translate(384,28)\"><\/path><path d=\"M0 0 C2.95640997 2.19762194 3.69767575 4.61266342 4.75 8.0625 C7.78935599 16.75780039 13.01265066 23.02281039 19.25 29.6875 C25.9634175 36.97140517 27.97358498 43.05474606 28 53 C26.74246318 72.92922483 14.05099812 95.94900188 0 110 C-1.65169622 110.60504844 -3.32172187 111.16065417 -5 111.6875 C-13.4068805 114.66881877 -19.61256977 119.63571361 -26.0625 125.6875 C-33.10333351 132.13518997 -40.3743043 135.29756855 -50 135 C-67.81834331 133.16006238 -82.99339386 125.59452323 -98.02392578 116.22949219 C-99.42176566 115.35977121 -100.82719955 114.50220023 -102.23779297 113.65332031 C-102.96240723 113.21342773 -103.68702148 112.77353516 -104.43359375 112.3203125 C-105.09286865 111.92344238 -105.75214355 111.52657227 -106.43139648 111.11767578 C-108 110 -108 110 -109 108 C-109.375 104.625 -109.375 104.625 -109 101 C-106.18645867 97.60434668 -102.93628524 96.59214147 -98.875 95.25 C-90.01209235 92.19669267 -83.37534425 86.16899844 -76.3125 80.1875 C-67.9196023 73.34097304 -61.03759701 71.88964849 -50.08789062 72.71484375 C-44.96739911 73.41418123 -40.11542111 75.17980128 -35.265625 76.90625 C-32.09987261 78.15879427 -32.09987261 78.15879427 -29 78 C-29.34933594 77.41734375 -29.69867188 76.8346875 -30.05859375 76.234375 C-35.7056514 66.06007284 -35.86698528 56.89454784 -33.1328125 45.69921875 C-28.23724822 29.71266917 -19.45450503 14.03193148 -9 1 C-5.95016004 -0.52491998 -3.3576631 -0.23562548 0 0 Z M-7 24 C-18.63579092 43.35450284 -18.63579092 43.35450284 -20 65 C-17.42591767 69.08224511 -14.2769229 72.47380246 -11 76 C-9.64708127 77.67183879 -8.31168942 79.35812185 -7 81.0625 C-6.443125 81.77535156 -5.88625 82.48820312 -5.3125 83.22265625 C-4 85 -4 85 -3 87 C1.38726015 85.53757995 2.42456283 82.14920352 4.4375 78.25 C4.83638428 77.48373291 5.23526855 76.71746582 5.64624023 75.92797852 C10.04996736 67.24433108 14.24094382 57.92755054 13 48 C11.03904402 44.22424626 8.60112952 41.3296913 5.6875 38.25 C2.02100359 34.27298598 -1.00371366 30.23604987 -3.80859375 25.6171875 C-4.20175781 25.08351563 -4.59492188 24.54984375 -5 24 C-5.66 24 -6.32 24 -7 24 Z M-73.67578125 97.02734375 C-76.91399688 99.77574525 -80.33287552 101.8664003 -84 104 C-82.75600609 107.73198172 -81.17811887 108.20773108 -77.78198242 109.90600586 C-77.07017822 110.24639893 -76.35837402 110.58679199 -75.625 110.9375 C-74.89837158 111.29013916 -74.17174316 111.64277832 -73.4230957 112.00610352 C-59.8293123 118.5506239 -59.8293123 118.5506239 -45 120 C-40.62791551 118.22631197 -37.57174475 115.93704844 -34.1875 112.6875 C-29.75077026 108.56719863 -25.14877297 105.17134567 -20 102 C-22.78910806 98.62149552 -26.58591438 96.95910733 -30.4375 95.0625 C-31.15180176 94.71058594 -31.86610352 94.35867187 -32.60205078 93.99609375 C-49.72704977 85.72277731 -59.22030904 83.89716101 -73.67578125 97.02734375 Z \" fill=\"#FFFFFF\" transform=\"translate(136,34)\"><\/path><path d=\"M0 0 C2.4296875 1.3203125 2.4296875 1.3203125 4.875 3.125 C34.77706662 22.99308437 80.05976261 23.95095302 114.64990234 24.40136719 C116.61318408 24.42891869 118.57616299 24.47590008 120.5390625 24.5234375 C121.68584473 24.54325684 122.83262695 24.56307617 124.01416016 24.58349609 C127.29579704 25.04126163 128.68869332 25.65739509 131 28 C132.14853405 31.87630241 132.46431111 33.9973782 130.75 37.69921875 C126.29732068 41.42454278 121.61364766 40.60640272 116 40.4375 C114.80173584 40.41719727 113.60347168 40.39689453 112.36889648 40.37597656 C71.37620784 39.46805433 27.50337655 36.15209346 -8.125 14.0625 C-10.84957163 11.06547121 -11.14070216 9.01001142 -11 5 C-7.75418278 0.37716941 -5.51748106 -0.5731551 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(75,323)\"><\/path><path d=\"M0 0 C0.79913818 0.19239258 1.59827637 0.38478516 2.42163086 0.58300781 C5.91718052 1.48075195 9.4047507 2.40473811 12.88818359 3.34838867 C43.52436421 11.612337 74.52193012 15.12519407 106.2109375 15.71899414 C108.24378401 15.75865365 110.27606287 15.8100757 112.30859375 15.86328125 C113.49727051 15.8883374 114.68594727 15.91339355 115.91064453 15.93920898 C118.84508158 16.22809018 120.55823082 16.61530156 122.98828125 18.2421875 C124.54603061 21.35768622 124.55308747 24.8466263 123.98828125 28.2421875 C122.83740234 29.84057617 122.83740234 29.84057617 120.98828125 31.2421875 C118.32568359 31.63037109 118.32568359 31.63037109 115.07421875 31.640625 C113.24588501 31.64993042 113.24588501 31.64993042 111.38061523 31.65942383 C110.04148631 31.64713256 108.70237322 31.63300047 107.36328125 31.6171875 C106.68000763 31.61286713 105.99673401 31.60854675 105.29275513 31.60409546 C69.44676999 31.3411056 24.31247206 29.53748699 -8.01171875 13.2421875 C-10.07421875 10.9296875 -10.07421875 10.9296875 -11.01171875 8.2421875 C-10.42674215 4.58608376 -9.60726983 2.81969158 -6.94921875 0.2421875 C-3.83830621 -0.81684655 -3.05852542 -0.74389944 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(121.01171875,418.7578125)\"><\/path><path d=\"M0 0 C1.24265625 0.18949219 2.4853125 0.37898438 3.765625 0.57421875 C4.45591797 0.68169434 5.14621094 0.78916992 5.85742188 0.89990234 C10.1512415 1.56283703 14.45047961 2.18781632 18.75 2.8125 C20.0181958 3.00247559 20.0181958 3.00247559 21.31201172 3.19628906 C33.73387982 5.00666707 46.13622701 5.4895675 58.67382812 5.76757812 C59.82173828 5.80173828 60.96964844 5.83589844 62.15234375 5.87109375 C63.69523071 5.90867798 63.69523071 5.90867798 65.26928711 5.94702148 C68.24903369 6.26315943 70.45298679 6.90579886 73.125 8.25 C74.68274936 11.36549872 74.68980622 14.8544388 74.125 18.25 C72.95556641 19.84838867 72.95556641 19.84838867 71.125 21.25 C68.58251953 21.63818359 68.58251953 21.63818359 65.5078125 21.6484375 C64.35788818 21.65456055 63.20796387 21.66068359 62.02319336 21.66699219 C60.77803955 21.65313477 59.53288574 21.63927734 58.25 21.625 C56.9616626 21.61629883 55.6733252 21.60759766 54.34594727 21.59863281 C36.63503519 21.38434372 18.95854084 19.59060846 1.5625 16.25 C0.34904907 16.01941895 0.34904907 16.01941895 -0.88891602 15.78417969 C-4.83158406 14.95396337 -8.0293286 14.20456188 -10.875 11.25 C-11.89016295 7.52773583 -12.45435468 5.35077389 -10.625 1.875 C-7.17963305 -1.32426931 -4.35148959 -0.68872497 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(172.875,264.75)\"><\/path><path d=\"M0 0 C0.97308105 0.11859375 1.94616211 0.2371875 2.94873047 0.359375 C3.96725098 0.49859375 4.98577148 0.6378125 6.03515625 0.78125 C8.05702201 1.0230984 10.0791649 1.26263999 12.1015625 1.5 C13.67732056 1.69033813 13.67732056 1.69033813 15.28491211 1.88452148 C27.14264984 3.30458367 38.85916802 4.19857937 50.80883789 4.2265625 C51.83098389 4.24332031 52.85312988 4.26007813 53.90625 4.27734375 C55.2509436 4.28012329 55.2509436 4.28012329 56.62280273 4.28295898 C59.83927435 4.94734706 61.03726355 6.22094093 63.03515625 8.78125 C63.50434308 12.53474462 63.56652006 14.81973453 61.72265625 18.15625 C59.41262006 20.38072929 57.58057231 20.76682611 54.41333008 20.85058594 C50.89078886 20.75621036 47.36929894 20.6554112 43.84765625 20.53125 C42.5536792 20.48605225 41.25970215 20.44085449 39.92651367 20.39428711 C-1.14298731 18.70601687 -1.14298731 18.70601687 -8.65234375 12.59375 C-10.41198567 8.82308875 -10.13751708 6.7390225 -8.96484375 2.78125 C-5.95975376 -0.17652563 -4.11570408 -0.54521817 0 0 Z \" fill=\"#FFFFFF\" transform=\"translate(152.96484375,202.21875)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDuo-massage\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAppartement: les joies de la vie en communaut\u00e9 <b>corps entier<\/b> massage. Un moment de d\u00e9tente pour les couples, les amis ou la famille.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eb3fbc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6eb3fbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-24ce1a7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"24ce1a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/duo-massage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apprendre plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82eabbf e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"82eabbf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d731cff elementor-widget elementor-widget-image\" data-id=\"d731cff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"391\" height=\"392\" src=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2026\/03\/4-handen-closer.png\" class=\"attachment-full size-full wp-image-989882\" alt=\"\" srcset=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2026\/03\/4-handen-closer.png 391w, https:\/\/asianmassage.be\/wp-content\/uploads\/2026\/03\/4-handen-closer-300x300.png 300w, https:\/\/asianmassage.be\/wp-content\/uploads\/2026\/03\/4-handen-closer-150x150.png 150w\" sizes=\"(max-width: 391px) 100vw, 391px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad09703 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ad09703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"50\" height=\"50\"><path d=\"M0 0 C0.70125 0.00515625 1.4025 0.0103125 2.125 0.015625 C2.82625 0.01046875 3.5275 0.0053125 4.25 0 C6.125 0.265625 6.125 0.265625 8.125 2.265625 C8.390625 4.140625 8.390625 4.140625 8.375 6.265625 C8.38015625 6.966875 8.3853125 7.668125 8.390625 8.390625 C8.125 10.265625 8.125 10.265625 6.125 12.265625 C4 12.890625 4 12.890625 2.125 13.265625 C3.06101246 14.68327494 3.9988792 16.09970068 4.9375 17.515625 C5.45957031 18.30453125 5.98164063 19.0934375 6.51953125 19.90625 C7.99634122 22.07654981 9.53189873 24.17976268 11.125 26.265625 C11.61871094 25.41097656 12.11242187 24.55632813 12.62109375 23.67578125 C13.26175781 22.57105469 13.90242188 21.46632813 14.5625 20.328125 C15.20058594 19.22597656 15.83867187 18.12382812 16.49609375 16.98828125 C18.125 14.265625 18.125 14.265625 19.125 13.265625 C18.320625 12.95625 17.51625 12.646875 16.6875 12.328125 C14.125 11.265625 14.125 11.265625 13.125 10.265625 C12.85185185 4.52951389 12.85185185 4.52951389 13.125 2.265625 C15.125 0.265625 15.125 0.265625 17 0 C17.70125 0.00515625 18.4025 0.0103125 19.125 0.015625 C19.82625 0.01046875 20.5275 0.0053125 21.25 0 C23.125 0.265625 23.125 0.265625 25.125 2.265625 C25.39491906 4.95401885 25.21237357 7.55704436 25.125 10.265625 C26.053125 10.4925 26.98125 10.719375 27.9375 10.953125 C31.125 12.265625 31.125 12.265625 33 14.453125 C34.36861955 17.87467388 34.33985027 20.6131704 34.125 24.265625 C31.48034962 21.1401291 30.28085285 18.17774233 29.125 14.265625 C24.41938426 15.1211915 22.75860597 15.4743803 19.69140625 19.3046875 C19.00146086 20.48745103 18.33367837 21.68339356 17.6875 22.890625 C17.33751953 23.50164063 16.98753906 24.11265625 16.62695312 24.7421875 C15.77332223 26.23896496 14.94636444 27.75090096 14.125 29.265625 C14.785 29.595625 15.445 29.925625 16.125 30.265625 C16.3725 29.523125 16.62 28.780625 16.875 28.015625 C18.21647301 25.06438438 19.73405526 23.41747526 22.125 21.265625 C23.115 24.235625 24.105 27.205625 25.125 30.265625 C28.095 30.265625 31.065 30.265625 34.125 30.265625 C34.125 30.925625 34.125 31.585625 34.125 32.265625 C30.825 32.265625 27.525 32.265625 24.125 32.265625 C24.125 37.545625 24.125 42.825625 24.125 48.265625 C27.425 48.265625 30.725 48.265625 34.125 48.265625 C34.125 48.925625 34.125 49.585625 34.125 50.265625 C30.165 50.265625 26.205 50.265625 22.125 50.265625 C22.125 47.955625 22.125 45.645625 22.125 43.265625 C20.0829172 43.27168459 18.04094299 43.32213698 16 43.390625 C14.29457031 43.42542969 14.29457031 43.42542969 12.5546875 43.4609375 C8.92522952 44.31249598 8.537101 44.64331414 6.27734375 47.29296875 C4.50805926 49.25805875 3.58171262 50.15723132 0.98535156 50.7734375 C-1.43074651 50.88997279 -3.77280022 50.84060991 -6.1875 50.703125 C-7.01056641 50.68443359 -7.83363281 50.66574219 -8.68164062 50.64648438 C-14.6770169 50.4636081 -14.6770169 50.4636081 -15.875 49.265625 C-15.91563832 47.59945385 -15.917721 45.93174405 -15.875 44.265625 C-13.895 43.605625 -11.915 42.945625 -9.875 42.265625 C-10.535 41.605625 -11.195 40.945625 -11.875 40.265625 C-12.140625 38.390625 -12.140625 38.390625 -12.125 36.265625 C-12.13015625 35.564375 -12.1353125 34.863125 -12.140625 34.140625 C-11.875 32.265625 -11.875 32.265625 -9.875 30.265625 C-6.75 30.140625 -6.75 30.140625 -3.875 30.265625 C-2.885 27.295625 -1.895 24.325625 -0.875 21.265625 C2.20589673 24.03843206 3.81275452 26.32888856 5.125 30.265625 C5.785 29.935625 6.445 29.605625 7.125 29.265625 C5.96302912 27.12276962 4.77379379 25.00536996 3.5625 22.890625 C3.23958984 22.28734375 2.91667969 21.6840625 2.58398438 21.0625 C0.60966315 17.67794933 -0.93181549 15.91457057 -4.65234375 14.8515625 C-5.71582031 14.65820312 -6.77929688 14.46484375 -7.875 14.265625 C-8.101875 15.049375 -8.32875 15.833125 -8.5625 16.640625 C-10.28160933 21.38864125 -12.55584721 25.78665052 -14.875 30.265625 C-15.205 30.265625 -15.535 30.265625 -15.875 30.265625 C-16.81072834 23.24766248 -14.03192822 17.86437067 -9.875 12.265625 C-6.5 10.578125 -6.5 10.578125 -3.875 10.265625 C-3.91625 8.986875 -3.9575 7.708125 -4 6.390625 C-4.0703125 4.2109375 -4.0703125 4.2109375 -3.875 2.265625 C-1.875 0.265625 -1.875 0.265625 0 0 Z M0.125 3.265625 C-0.205 4.915625 -0.535 6.565625 -0.875 8.265625 C1.6 8.760625 1.6 8.760625 4.125 9.265625 C4.455 7.615625 4.785 5.965625 5.125 4.265625 C3.475 3.935625 1.825 3.605625 0.125 3.265625 Z M17.125 3.265625 C16.795 4.915625 16.465 6.565625 16.125 8.265625 C18.6 8.760625 18.6 8.760625 21.125 9.265625 C21.455 7.615625 21.785 5.965625 22.125 4.265625 C20.475 3.935625 18.825 3.605625 17.125 3.265625 Z M0.125 28.265625 C-0.865 29.750625 -0.865 29.750625 -1.875 31.265625 C-1.545 31.595625 -1.215 31.925625 -0.875 32.265625 C-0.50739269 34.59380464 -0.17258419 36.9274635 0.125 39.265625 C0.455 39.265625 0.785 39.265625 1.125 39.265625 C1.3415625 37.595 1.3415625 37.595 1.5625 35.890625 C2.125 32.265625 2.125 32.265625 3.125 30.265625 C2.465 30.265625 1.805 30.265625 1.125 30.265625 C0.795 29.605625 0.465 28.945625 0.125 28.265625 Z M20.125 28.265625 C20.125 28.925625 20.125 29.585625 20.125 30.265625 C20.785 29.935625 21.445 29.605625 22.125 29.265625 C21.465 28.935625 20.805 28.605625 20.125 28.265625 Z M4.71484375 34.05078125 C2.6353133 36.94781753 1.96852581 39.82663516 1.125 43.265625 C-0.68615956 45.07678456 -3.48778227 44.64761948 -5.9375 44.828125 C-7.04222656 44.91191406 -8.14695312 44.99570312 -9.28515625 45.08203125 C-10.13980469 45.14261719 -10.99445312 45.20320313 -11.875 45.265625 C-11.875 46.255625 -11.875 47.245625 -11.875 48.265625 C-4.6947447 49.2702497 -4.6947447 49.2702497 1.6953125 46.96484375 C2.08460937 46.42472656 2.47390625 45.88460937 2.875 45.328125 C5.13190982 42.38583459 6.22651876 42.24951574 10.0390625 41.64453125 C14.0664967 41.35500923 18.08801596 41.27521404 22.125 41.265625 C22.125 38.295625 22.125 35.325625 22.125 32.265625 C19.7071288 32.15736211 17.29412444 32.07822711 14.875 32.015625 C13.85212891 31.96535156 13.85212891 31.96535156 12.80859375 31.9140625 C9.38715161 31.84762673 7.49909294 31.98854158 4.71484375 34.05078125 Z M-7.875 33.265625 C-8.205 34.915625 -8.535 36.565625 -8.875 38.265625 C-6.4 38.760625 -6.4 38.760625 -3.875 39.265625 C-3.545 37.615625 -3.215 35.965625 -2.875 34.265625 C-4.525 33.935625 -6.175 33.605625 -7.875 33.265625 Z \" fill=\"#FFFFFF\" transform=\"translate(15.875,-0.265625)\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<span style=\"font-family: &quot;Libre Baskerville&quot;, sans-serif;font-size: 24px;font-style: normal;font-weight: 400\">Massage \u00e0 quatre mains<\/span>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tD\u00e9couvrez la relaxation ultime avec notre <b>corps entier<\/b> massage \u00e0 quatre mains, o\u00f9 deux masseuses offrent simultan\u00e9ment une relaxation profonde, un soulagement intense et une pure indulgence.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-421434d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"421434d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-c9f65fe elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c9f65fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/Vier-handen-massage\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Apprendre plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende spierlagen. Helpt bij stramme spieren en opgehoopte spanning. Leer meer Rug-, Nek- &amp; Schoudermassage Perfect voor wie dagelijks veel spanning vasthoudt in de bovenrug, bijvoorbeeld door bureauwerk of stress. Leer meer Voetreflexmassage Een verfrissende behandeling die de drukpunten in je voeten stimuleert en je hele lichaam laat ontspannen. Leer meer Duo-massage Samen genieten in \u00e9\u00e9n kamer van een full body massage. Een rustmoment voor koppels, vrienden of familie. Leer meer Quatre mains-massage Ervaar ultieme ontspanning met onze full body vierhandenmassage, waarbij twee masseuses gelijktijdig zorgen voor diepe rust, intense verlichting en pure verwennerij. Leer meer<\/p>","protected":false},"author":2,"featured_media":9195,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-23","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/asianmassage.be\/fr\/behandelingen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Healthy Asian Massage - Bij ons ben je in goede handen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Behandelingen - Healthy Asian Massage\" \/>\n\t\t<meta property=\"og:description\" content=\"Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/asianmassage.be\/fr\/behandelingen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/12\/cropped-cropped-Untitled-design.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/12\/cropped-cropped-Untitled-design.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-09-03T08:27:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-08T16:09:26+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Behandelingen - Healthy Asian Massage\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/12\/cropped-cropped-Untitled-design.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/asianmassage.be\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#listItem\",\"name\":\"Behandelingen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#listItem\",\"position\":2,\"name\":\"Behandelingen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/#organization\",\"name\":\"Healthy Asian Massage\",\"description\":\"Bij ons ben je in goede handen\",\"url\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/asianmassage.be\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cropped-cropped-Untitled-design.png\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#organizationLogo\",\"width\":539,\"height\":539},\"image\":{\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#webpage\",\"url\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/\",\"name\":\"Behandelingen - Healthy Asian Massage\",\"description\":\"Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/asianmassage.be\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ChatGPT-Image-Dec-3-2025-11_39_47-AM.png\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#mainImage\",\"width\":1536,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/behandelingen\\\/#mainImage\"},\"datePublished\":\"2025-09-03T08:27:34+00:00\",\"dateModified\":\"2026-07-08T16:09:26+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/\",\"name\":\"Healthy Asian Massage\",\"description\":\"Bij ons ben je in goede handen\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/asianmassage.be\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Behandelingen - Healthy Asian Massage","description":"Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende","canonical_url":"https:\/\/asianmassage.be\/fr\/behandelingen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/asianmassage.be\/fr#listItem","position":1,"name":"Home","item":"https:\/\/asianmassage.be\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#listItem","name":"Behandelingen"}},{"@type":"ListItem","@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#listItem","position":2,"name":"Behandelingen","previousItem":{"@type":"ListItem","@id":"https:\/\/asianmassage.be\/fr#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/asianmassage.be\/fr\/#organization","name":"Healthy Asian Massage","description":"Bij ons ben je in goede handen","url":"https:\/\/asianmassage.be\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/12\/cropped-cropped-Untitled-design.png","@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#organizationLogo","width":539,"height":539},"image":{"@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#webpage","url":"https:\/\/asianmassage.be\/fr\/behandelingen\/","name":"Behandelingen - Healthy Asian Massage","description":"Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/asianmassage.be\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-Dec-3-2025-11_39_47-AM.png","@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#mainImage","width":1536,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/asianmassage.be\/fr\/behandelingen\/#mainImage"},"datePublished":"2025-09-03T08:27:34+00:00","dateModified":"2026-07-08T16:09:26+00:00"},{"@type":"WebSite","@id":"https:\/\/asianmassage.be\/fr\/#website","url":"https:\/\/asianmassage.be\/fr\/","name":"Healthy Asian Massage","description":"Bij ons ben je in goede handen","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/asianmassage.be\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Healthy Asian Massage - Bij ons ben je in goede handen","og:type":"article","og:title":"Behandelingen - Healthy Asian Massage","og:description":"Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende","og:url":"https:\/\/asianmassage.be\/fr\/behandelingen\/","og:image":"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/12\/cropped-cropped-Untitled-design.png","og:image:secure_url":"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/12\/cropped-cropped-Untitled-design.png","article:published_time":"2025-09-03T08:27:34+00:00","article:modified_time":"2026-07-08T16:09:26+00:00","twitter:card":"summary_large_image","twitter:title":"Behandelingen - Healthy Asian Massage","twitter:description":"Onze behandelingen Erotische of sensuele massages maken geen deel uit van ons aanbod. Traditionele Aziatische Ontspanningsmassage Een zachte, vloeiende full body massage die helpt om je lichaam volledig tot rust te brengen. Ideaal bij stress of vermoeidheid. Leer meer Deep Tissue Massage Een intensievere full body massage, ook wel eens sportmassage genoemd, gericht op dieperliggende","twitter:image":"https:\/\/asianmassage.be\/wp-content\/uploads\/2025\/12\/cropped-cropped-Untitled-design.png"},"aioseo_meta_data":{"post_id":"23","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-29 06:18:10","updated":"2026-07-08 16:36:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/asianmassage.be\/fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBehandelingen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/asianmassage.be\/fr"},{"label":"Behandelingen","link":"https:\/\/asianmassage.be\/fr\/behandelingen\/"}],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/pages\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":150,"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/pages\/23\/revisions"}],"predecessor-version":[{"id":990135,"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/pages\/23\/revisions\/990135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/media\/9195"}],"wp:attachment":[{"href":"https:\/\/asianmassage.be\/fr\/wp-json\/wp\/v2\/media?parent=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}